{"id":32245,"date":"2020-06-29T16:19:18","date_gmt":"2020-06-29T14:19:18","guid":{"rendered":"https:\/\/energy-cities.eu\/?p=32245"},"modified":"2020-07-16T14:29:56","modified_gmt":"2020-07-16T12:29:56","slug":"la-renovation-energetique-dans-le-plan-de-relance-francais","status":"publish","type":"post","link":"https:\/\/energy-cities.eu\/fr\/la-renovation-energetique-dans-le-plan-de-relance-francais\/","title":{"rendered":"La r\u00e9novation \u00e9nerg\u00e9tique dans le plan de relance fran\u00e7ais"},"content":{"rendered":"\n<p><em>Cet article a d&rsquo;abord \u00e9t\u00e9 publi\u00e9 dans le <a href=\"https:\/\/www.iddri.org\/fr\/publications-et-evenements\/billet-de-blog\/la-renovation-energetique-dans-le-plan-de-relance\">blog d&rsquo;IDDRI<\/a>. Nous le republions avec l&rsquo;accord de son auteur, <a href=\"https:\/\/www.iddri.org\/fr\/iddri-en-bref\/equipe\/andreas-rudinger\">Andreas R\u00fcdinger, chercheur associ\u00e9<\/a>.<\/em><\/p>\n\n\n\n<p><strong>La r\u00e9novation \u00e9nerg\u00e9tique repr\u00e9sente une priorit\u00e9 pour les plans de relance post-crise, que ce soit \u00e0 l\u2019\u00e9chelle de la France, de l\u2019Union europ\u00e9enne ou du monde<a href=\"https:\/\/www.iddri.org\/fr\/publications-et-evenements\/billet-de-blog\/la-renovation-energetique-dans-le-plan-de-relance#footnote1_djnoo38\">1<\/a>. Cette urgence s\u2019explique \u00e0 la fois par son potentiel \u00e9conomique rapidement mobilisable, son r\u00f4le cl\u00e9 pour les politiques climatiques, et par l\u2019importance de la lutte contre la pr\u00e9carit\u00e9 \u00e9nerg\u00e9tique dans un contexte d\u2019augmentation des vuln\u00e9rabilit\u00e9s. Alors que les propositions fran\u00e7aises de plans de relance abondent<a href=\"https:\/\/www.iddri.org\/fr\/publications-et-evenements\/billet-de-blog\/la-renovation-energetique-dans-le-plan-de-relance#footnote2_wsmy60l\">2<\/a>, il s\u2019agit d\u00e9sormais d\u2019identifier les leviers les plus efficaces permettant de combiner reprise \u00e9conomique et mont\u00e9e en puissance du march\u00e9 de la r\u00e9novation globale et performante, condition indispensable pour se placer sur une trajectoire convergente avec la strat\u00e9gie nationale bas-carbone fran\u00e7aise.<\/strong><\/p>\n\n\n\n<h2>Un secteur cl\u00e9 avec un retard croissant sur les objectifs<\/h2>\n\n\n\n<p>\u00c0 eux seuls, les b\u00e2timents repr\u00e9sentent 45 % de l\u2019\u00e9nergie consomm\u00e9e en France (dont les deux tiers pour le r\u00e9sidentiel et un tiers pour le tertiaire)<a href=\"https:\/\/www.iddri.org\/fr\/publications-et-evenements\/billet-de-blog\/la-renovation-energetique-dans-le-plan-de-relance#footnote3_t2bmzq3\">3<\/a>. Cette consommation d\u2019\u00e9nergie repr\u00e9sente 28 % des \u00e9missions de gaz \u00e0 effets de serre en France<a href=\"https:\/\/www.iddri.org\/fr\/publications-et-evenements\/billet-de-blog\/la-renovation-energetique-dans-le-plan-de-relance#footnote4_7k6l5u2\">4<\/a>&nbsp;; des \u00e9missions qui n\u2019ont quasiment pas recul\u00e9 depuis 1990 (-3 %), faisant de ce secteur la \u00ab lanterne rouge \u00bb du premier budget carbone (2015-2018) avec un d\u00e9passement de 12 % par rapport \u00e0 l\u2019objectif sectoriel. Ce constat s\u2019explique essentiellement par&nbsp;<a href=\"https:\/\/www.iddri.org\/sites\/default\/files\/PDF\/Publications\/Catalogue%20Iddri\/Etude\/201810-ST12118FR-bilan%20transition.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">la lenteur des progr\u00e8s dans le secteur de la r\u00e9novation \u00e9nerg\u00e9tique<\/a>. Face \u00e0 l\u2019objectif de porter l\u2019ensemble du parc des logements au niveau de performance \u00ab b\u00e2timent basse consommation \u00bb (BBC) d\u2019ici 2050 et de r\u00e9nover 500 000 logements par an, les progr\u00e8s restent timides, pour autant qu\u2019on puisse&nbsp;<a href=\"https:\/\/www.lemonde.fr\/planete\/article\/2020\/06\/09\/l-impossible-evaluation-du-nombre-de-batiments-basse-consommation_6042243_3244.html\" target=\"_blank\" rel=\"noreferrer noopener\">les mesurer en l\u2019absence de donn\u00e9es fiables sur le nombre et la qualit\u00e9 des r\u00e9novations<\/a><a href=\"https:\/\/www.iddri.org\/fr\/publications-et-evenements\/billet-de-blog\/la-renovation-energetique-dans-le-plan-de-relance#footnote5_sa122w9\">5<\/a>.<\/p>\n\n\n\n<h2>Un potentiel \u00e9conomique et un gisement d&#8217;emplois consid\u00e9rables<\/h2>\n\n\n\n<p><a href=\"https:\/\/www.ademe.fr\/sites\/default\/files\/assets\/documents\/marches-emplois-secteur-batiment-residentiel-2019.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">L\u2019\u00e9tude March\u00e9s &amp; Emplois de l\u2019Ademe<\/a>&nbsp;indique que le secteur de la r\u00e9novation \u00e9nerg\u00e9tique repr\u00e9sentait plus de 200 000 emplois et un chiffre d\u2019affaires de 29 milliards d\u2019euros en 2016. Selon les hypoth\u00e8ses du&nbsp;<a href=\"http:\/\/renovons.org\/IMG\/pdf\/sce_nario_re_novons_2020_vf.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">sc\u00e9nario \u00ab R\u00e9novons \u00bb<\/a>, un plan ambitieux d\u2019\u00e9radication des passoires \u00e9nerg\u00e9tiques (logements de classes \u00e9nerg\u00e9tiques F et G) pourrait cr\u00e9er jusqu\u2019\u00e0 93 000 emplois suppl\u00e9mentaires sur dix ans ; une estimation qui rejoint l\u2019\u00e9valuation r\u00e9alis\u00e9e par I4CE dans une&nbsp;<a href=\"https:\/\/www.i4ce.org\/wp-core\/wp-content\/uploads\/2020\/04\/I4CE-Investir-pour-le-climat-sortie-de-crise-COVID-1.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">analyse r\u00e9cente<\/a>&nbsp;et qui identifie des pistes pour doubler en 5 ans les investissements orient\u00e9s vers les r\u00e9novations tr\u00e8s performantes.<\/p>\n\n\n\n<h2>\u00c9viter le pi\u00e8ge d\u2019une action focalis\u00e9e exclusivement sur le court terme<\/h2>\n\n\n\n<p>En contexte de sortie de crise, face \u00e0 l\u2019imp\u00e9ratif de g\u00e9n\u00e9rer des impacts \u00e9conomiques \u00e0 court terme, la tentation peut \u00eatre grande de limiter les mesures du plan de relance \u00e0 des actions rapidement mobilisables, en s\u2019appuyant exclusivement sur un renforcement des outils d\u2019aide \u00e0 la r\u00e9novation existants, notamment&nbsp;<em>via<\/em>&nbsp;un \u00e9largissement des crit\u00e8res d\u2019\u00e9ligibilit\u00e9 du cr\u00e9dit d\u2019imp\u00f4t transition \u00e9nerg\u00e9tique (r\u00e9int\u00e9grant les m\u00e9nages les plus ais\u00e9s), voire une augmentation des taux d\u2019aide. Une telle approche comporte deux risques majeurs. D\u2019une part, l\u2019accroissement du volume d\u2019activit\u00e9 s\u2019estomperait rapidement apr\u00e8s la disparition des mesures exceptionnelles, cr\u00e9ant de fait une \u00ab bulle \u00bb d\u2019activit\u00e9 sans impact durable dans le temps. D\u2019autre part, s\u2019appuyer exclusivement sur les outils existants comporte le risque de conserver, voire d\u2019amplifier leurs d\u00e9fauts. En l\u2019occurrence, celui de ne favoriser que des gestes uniques et disparates de r\u00e9novation \u00e9nerg\u00e9tique, d\u00e9connect\u00e9s et souvent incompatibles avec la logique d\u2019une r\u00e9novation performante au niveau \u00ab BBC \u00bb. Et d\u2019augmenter les risques d\u2019effets d\u2019aubaine en cas de subventions fl\u00e9ch\u00e9es sur des \u00e9quipements pr\u00e9cis, r\u00e9duisant d\u2019autant l\u2019efficacit\u00e9 \u00e9conomique des dispositifs<a href=\"https:\/\/www.iddri.org\/fr\/publications-et-evenements\/billet-de-blog\/la-renovation-energetique-dans-le-plan-de-relance#footnote6_8u4d1pp\">6<\/a>.<\/p>\n\n\n\n<h2>D\u00e9clencher le march\u00e9 de la r\u00e9novation globale en France via le plan de relance<\/h2>\n\n\n\n<p>\u00c0 l\u2019inverse, une strat\u00e9gie coh\u00e9rente avec les objectifs fix\u00e9s doit viser \u00e0 combiner des mesures pouvant g\u00e9n\u00e9rer un accroissement d\u2019activit\u00e9 \u00e0 tr\u00e8s court terme avec des actions visant \u00e0 saisir cette opportunit\u00e9 pour engager r\u00e9solument le changement d\u2019\u00e9chelle du march\u00e9 de la r\u00e9novation globale et performante qui fait encore d\u00e9faut. Une telle strat\u00e9gie pourrait se fonder sur plusieurs orientations.<\/p>\n\n\n\n<p>\u00c0 court terme, int\u00e9grer une aide massive et directement fl\u00e9ch\u00e9e vers la r\u00e9novation performante \u00ab BBC \u00bb dans les dispositifs existants (Prime R\u00e9nov de l\u2019ANAH, CITE, Certificats d\u2019\u00e9conomie d\u2019\u00e9nergie) afin d\u2019\u00e9liminer un paradoxe important de la politique de r\u00e9novation fran\u00e7aise : face \u00e0 l\u2019objectif de porter l\u2019ensemble du parc des logements \u00e0 un niveau \u00ab BBC \u00bb en 2050, pas un seul outil d\u2019aide national n\u2019est pour l\u2019instant conditionn\u00e9 \u00e0 l\u2019atteinte de ce niveau de performance, freinant de fait l\u2019\u00e9mergence de ce march\u00e9. Le montant de cette aide devrait \u00eatre \u00e0 la hauteur des enjeux, afin de fournir un signal clair et cr\u00e9dible \u00e0 l\u2019ensemble des acteurs (propri\u00e9taires, artisans du b\u00e2timent) sur l\u2019\u00e9largissement du march\u00e9 de la r\u00e9novation globale<a href=\"https:\/\/www.iddri.org\/fr\/publications-et-evenements\/billet-de-blog\/la-renovation-energetique-dans-le-plan-de-relance#footnote7_j85hq0q\">7<\/a>.<\/p>\n\n\n\n<p>Sur la base des&nbsp;<a href=\"https:\/\/propositions.conventioncitoyennepourleclimat.fr\/\" target=\"_blank\" rel=\"noreferrer noopener\">recommandations issus de la Convention citoyenne pour le climat<\/a>, il s\u2019agit ensuite de viser \u00e0 moyen terme une refonte de l\u2019ensemble des dispositifs existants, afin de cr\u00e9er une strat\u00e9gie coh\u00e9rente autour de trois axes compl\u00e9mentaires :<\/p>\n\n\n\n<ul><li>un dispositif d\u2019aide unique et simple pour les m\u00e9nages, modul\u00e9 en fonction de leurs ressources et du niveau de performance \u00e9nerg\u00e9tique atteint apr\u00e8s travaux, et distribu\u00e9 par des guichets uniques territoriaux qui assurent l\u2019accompagnement des propri\u00e9taires pendant toutes les phases du projet (du diagnostic initial jusqu\u2019\u00e0 l\u2019\u00e9valuation de la qualit\u00e9 des travaux, en passant par l\u2019ing\u00e9nierie financi\u00e8re et le montage technique du projet), en mobilisant l\u2019ensemble des acteurs publics et priv\u00e9s<a href=\"https:\/\/www.iddri.org\/fr\/publications-et-evenements\/billet-de-blog\/la-renovation-energetique-dans-le-plan-de-relance#footnote8_5j1x4ly\">8<\/a>.<\/li><li>une visibilit\u00e9 \u00e0 long terme sur la mise en place et l\u2019\u00e9volution dans le temps des obligations de r\u00e9novation \u00e9nerg\u00e9tique en coh\u00e9rence avec l\u2019objectif d\u2019un parc \u00ab BBC \u00bb en 2050 : afin d\u2019\u00e9viter les \u00ab effets de seuil \u00bb (passage de la classe F ou G en classe E, sans aller plus loin) et inciter les acteurs \u00e0 pr\u00e9voir d\u00e8s \u00e0 pr\u00e9sent des r\u00e9novations performantes.<\/li><li>un soutien \u00e0 la structuration d\u2019une offre de la r\u00e9novation globale comp\u00e9titive et de qualit\u00e9, capable de suivre l\u2019acc\u00e9l\u00e9ration du march\u00e9 : en multipliant les initiatives de formation sur site et de structuration de groupements d\u2019artisans locaux, en am\u00e9liorant la fiabilit\u00e9 et l\u2019opposabilit\u00e9 des diagnostics de performance \u00e9nerg\u00e9tique et en faisant de la r\u00e9novation \u00ab BBC \u00bb une composante centrale de la formation initiale des m\u00e9tiers du b\u00e2timent.<\/li><\/ul>\n\n\n\n<p>L\u2019enjeu est donc double : il s\u2019agit de fournir un signal fort pour cr\u00e9er un sursaut du march\u00e9 de la r\u00e9novation \u00e9nerg\u00e9tique performante \u00e0 court terme (certains \u00e9voquent le terme de \u00ab&nbsp;<a href=\"https:\/\/www.euractiv.fr\/section\/climat\/news\/pascal-canfin-evoque-un-plan-marshall-pour-la-renovation-des-batiments\/\" target=\"_blank\" rel=\"noreferrer noopener\">Plan Marshall du b\u00e2timent<\/a>&nbsp;\u00bb ; mais cet effort doit \u00eatre orient\u00e9 pour pr\u00e9parer le terrain \u00e0 la mise en \u0153uvre des orientations strat\u00e9giques \u00e9mises par la Convention citoyenne pour le Climat. Mise en \u0153uvre qui pourrait \u00eatre d\u00e9taill\u00e9e dans le cadre de l\u2019\u00e9laboration de la feuille de route quinquennale de la r\u00e9novation \u00e9nerg\u00e9tique des b\u00e2timents inscrite \u00e0 l\u2019article 1 de la loi \u00e9nergie-climat de 2019.<\/p>\n\n\n\n<ul><li><em><a href=\"https:\/\/www.iddri.org\/fr\/publications-et-evenements\/billet-de-blog\/la-renovation-energetique-dans-le-plan-de-relance#footnoteref1_djnoo38\">1.<\/a>&nbsp;<a href=\"https:\/\/www.iea.org\/news\/iea-offers-world-governments-a-sustainable-recovery-plan-to-boost-economic-growth-create-millions-of-jobs-and-put-emissions-into-structural-decline\">https:\/\/www.iea.org\/news\/iea-offers-world-governments-a-sustainable-recovery-plan-to-boost-economic-growth-create-millions-of-jobs-and-put-emissions-into-structural-decline<\/a><\/em><\/li><li><em><a href=\"https:\/\/www.iddri.org\/fr\/publications-et-evenements\/billet-de-blog\/la-renovation-energetique-dans-le-plan-de-relance#footnoteref2_wsmy60l\">2.<\/a>&nbsp;Pour aller plus loin, voici une liste (non exhaustive) des propositions pour le plan de relance focalis\u00e9es sur le sujet de la r\u00e9novation \u00e9nerg\u00e9tique : S\u00e9nat (<a href=\"http:\/\/www.senat.fr\/fileadmin\/Fichiers\/Images\/commission\/affaires_eco\/Covid-19\/Feuille_de_route_relance_energie_04-06-2020.pdf\">http:\/\/www.senat.fr\/fileadmin\/Fichiers\/Images\/commission\/affaires_eco\/Covid-19\/Feuille_de_route_relance_energie_04-06-2020.pdf<\/a>); N\u00e9gawatt (<a href=\"https:\/\/www.negawatt.org\/IMG\/pdf\/200611_note_plan-de-relance_reno-performante.pdf\">https:\/\/www.negawatt.org\/IMG\/pdf\/200611_note_plan-de-relance_reno-performante.pdf<\/a>); I4CE (<a href=\"https:\/\/www.i4ce.org\/wp-core\/wp-content\/uploads\/2020\/04\/I4CE-Investir-pour-le-climat-sortie-de-crise-COVID-1.pdf\">https:\/\/www.i4ce.org\/wp-core\/wp-content\/uploads\/2020\/04\/I4CE-Investir-pour-le-climat-sortie-de-crise-COVID-1.pdf<\/a>); CSCEE (<a href=\"https:\/\/www.actu-environnement.com\/media\/pdf\/news-35644-cscee-relance-propositions-secteur.pdf\">https:\/\/www.actu-environnement.com\/media\/pdf\/news-35644-cscee-relance-propositions-secteur.pdf<\/a>); Convention citoyenne pour le Climat ( ) ; Association des r\u00e9gions de France (<a href=\"http:\/\/regions-france.org\/wp-content\/uploads\/2020\/04\/20200406-DP-relance.pdf\">http:\/\/regions-france.org\/wp-content\/uploads\/2020\/04\/20200406-DP-relance.pdf<\/a>). Il est \u00e9galement int\u00e9ressant de consulter la proposition de projet de loi sur la \u00ab Prime Climat \u00bb (<a href=\"https:\/\/lessocialistes.fr\/wp-content\/uploads\/2020\/05\/Groupe-Socialistes-et-apparente%CC%81s-Proposition-de-loi-Prime-pour-le-Climat-2020-1.pdf\">https:\/\/lessocialistes.fr\/wp-content\/uploads\/2020\/05\/Groupe-Socialistes-et-apparente%CC%81s-Proposition-de-loi-Prime-pour-le-Climat-2020-1.pdf<\/a>), port\u00e9e par le d\u00e9put\u00e9 Boris Vallaud, particuli\u00e8rement compl\u00e8te sur les enjeux d\u2019articulation entre une obligation progressive de r\u00e9novation \u00e9nerg\u00e9tique et une refonte des aides aux travaux.<\/em><\/li><\/ul>\n\n\n\n<ul><li><em><a href=\"https:\/\/www.iddri.org\/fr\/publications-et-evenements\/billet-de-blog\/la-renovation-energetique-dans-le-plan-de-relance#footnoteref3_t2bmzq3\">3.<\/a>&nbsp;La consommation d\u2019\u00e9nergie du secteur r\u00e9sidentiel-tertiaire est globalement stable (+4 % depuis 2000). Les \u00e9missions du b\u00e2timent ont baiss\u00e9 de seulement 3 % entre 1990 et 2007, les gains d\u2019efficacit\u00e9 et de d\u00e9carbonation de l\u2019\u00e9nergie ayant globalement \u00e9t\u00e9 \u00ab compens\u00e9s \u00bb par l\u2019augmentation des surfaces.<\/em><\/li><li><em><a href=\"https:\/\/www.iddri.org\/fr\/publications-et-evenements\/billet-de-blog\/la-renovation-energetique-dans-le-plan-de-relance#footnoteref4_7k6l5u2\">4.<\/a>&nbsp;Selon la nouvelle Strat\u00e9gie nationale bas-carbone adopt\u00e9e en 2020, le secteur r\u00e9sidentiel-tertiaire repr\u00e9sente 19 % des \u00e9missions nationales en Scope 1 et 28 % en scope 2, int\u00e9grant les \u00e9missions li\u00e9es \u00e0 la production d\u2019\u00e9nergie consomm\u00e9e dans les b\u00e2timents (notamment \u00e9lectricit\u00e9 et r\u00e9seaux de chaleur).<\/em><\/li><li><em><a href=\"https:\/\/www.iddri.org\/fr\/publications-et-evenements\/billet-de-blog\/la-renovation-energetique-dans-le-plan-de-relance#footnoteref5_sa122w9\">5.<\/a>&nbsp;Dans son premier rapport annuel de 2019, le Haut Conseil pour le climat (HCC) notait ainsi que : \u00ab L\u2019absence d\u2019exigence de r\u00e9sultat et de dispositif de contr\u00f4le pour la plupart des op\u00e9rations de r\u00e9novation thermique (m\u00eame lorsqu\u2019elles b\u00e9n\u00e9ficient d\u2019un soutien financier) fait qu\u2019il n\u2019y a ni qualit\u00e9 de r\u00e9sultat, ni donn\u00e9es fiables pour \u00e9valuer correctement les progr\u00e8s r\u00e9alis\u00e9s par rapport aux objectifs fix\u00e9s par la SNBC et l\u2019efficacit\u00e9 des aides \u00e0 la r\u00e9novation \u00bb.<\/em><\/li><li><em><a href=\"https:\/\/www.iddri.org\/fr\/publications-et-evenements\/billet-de-blog\/la-renovation-energetique-dans-le-plan-de-relance#footnoteref6_8u4d1pp\">6.<\/a>&nbsp;Le risque d\u2019effet d\u2019aubaine est particuli\u00e8rement important en raison du fl\u00e9chage des aides vers des \u00e9quipements (po\u00eales \u00e0 bois, pompes \u00e0 chaleur, fen\u00eatres) ou gestes de r\u00e9novation (isolation des combles, de la toiture, etc.) pr\u00e9cis, plut\u00f4t que de conserver une aide globale en fonction du niveau de performance atteint apr\u00e8s travaux. Pour une analyse plus d\u00e9taill\u00e9e, voir par exemple l\u2019\u00e9valuation des aides \u00e0 la r\u00e9novation publi\u00e9e par le CGEDD et l\u2019IGF en 2017 (<a href=\"https:\/\/cgedd.documentation.developpement-durable.gouv.fr\/documents\/Affaires-0009660\/010867-01_rapport.pdf\">https:\/\/cgedd.documentation.developpement-durable.gouv.fr\/documents\/Affaires-0009660\/010867-01_rapport.pdf<\/a>) ou encore cet article de Bozonnat et al. (2016) (<a href=\"https:\/\/hal-enpc.archives-ouvertes.fr\/hal-01336704\/document\">https:\/\/hal-enpc.archives-ouvertes.fr\/hal-01336704\/document<\/a>).<\/em><\/li><li><em><a href=\"https:\/\/www.iddri.org\/fr\/publications-et-evenements\/billet-de-blog\/la-renovation-energetique-dans-le-plan-de-relance#footnoteref7_j85hq0q\">7.<\/a>&nbsp;En termes de montant de l\u2019aide \u00e0 la r\u00e9novation globale, la comparaison avec le dispositif allemand de la KfW (r\u00e9cemment renforc\u00e9) peut servir de r\u00e9f\u00e9rence : en France, le CITE finance au maximum 4 800 euros pour un couple, la prime R\u00e9nov de l\u2019ANAH peut atteindre jusqu\u2019\u00e0 20 000 euros pour les m\u00e9nages tr\u00e8s modestes, d\u00e9pendant avant tout des gestes de r\u00e9novation pr\u00e9vus. En Allemagne, les r\u00e9novations tr\u00e8s performantes sont subventionn\u00e9s jusqu\u2019\u00e0 48 000 euros par logement (maximum 40 % de l\u2019investissement global), aide uniquement conditionn\u00e9e \u00e0 l\u2019atteinte du niveau de performance vis\u00e9, ind\u00e9pendamment des travaux pr\u00e9vus et des revenus du m\u00e9nage.<\/em><\/li><li><em><a href=\"https:\/\/www.iddri.org\/fr\/publications-et-evenements\/billet-de-blog\/la-renovation-energetique-dans-le-plan-de-relance#footnoteref8_5j1x4ly\">8.<\/a>&nbsp;La notion de guichet unique n\u2019implique pas \u00e0 priori qu\u2019un seul acteur soit charg\u00e9 de l\u2019ensemble de l\u2019accompagnement des propri\u00e9taires, mais bien de constituer une interface unique qui facilite la coordination entre le propri\u00e9taire et l\u2019ensemble des acteurs intervenant \u00e0 diff\u00e9rentes phases du projet de r\u00e9novation (plateformes territoriales et espaces info \u00e9nergie, architectes, experts thermiciens, artisans, etc.). Pour plus de d\u00e9tails, voir ce rapport de l\u2019Ademe sur l\u2019accompagnement des m\u00e9nages dans la r\u00e9novation de leur logement (2019) (<a href=\"https:\/\/gbrisepierre.fr\/wp-content\/uploads\/2019\/12\/ADEME-2019-Accompagner-la-r%C3%A9novation-Rapport-synthetique.pdf\">https:\/\/gbrisepierre.fr\/wp-content\/uploads\/2019\/12\/ADEME-2019-Accompagner-la-r%C3%A9novation-Rapport-synthetique.pdf<\/a>).<\/em><\/li><\/ul>\n\n\n\n<p class=\"light-green-message\">Par ailleurs, Andreas R\u00fcdinger a aussi \u00e9t\u00e9 l&rsquo;auteur de notre \u00e9tude <a href=\"https:\/\/energy-cities.eu\/fr\/publication\/la-reappropriation-locale-de-lenergie-en-europe\/\">\u00ab\u00a0La r\u00e9appropriation locale de l&rsquo;\u00e9nergie en Europe\u00a0\u00bb<\/a> (2017).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alors que les propositions fran\u00e7aises de plans de relance abondent, il s\u2019agit d\u00e9sormais d\u2019identifier les leviers les plus efficaces permettant de combiner reprise \u00e9conomique et mont\u00e9e en puissance du march\u00e9 de la r\u00e9novation globale et performante, condition indispensable pour se placer sur une trajectoire convergente avec la strat\u00e9gie nationale bas-carbone fran\u00e7aise.<\/p>\n","protected":false},"author":25,"featured_media":32241,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","ub_ctt_via":""},"categories":[4,91],"tags":[],"hub":[309],"topic":[22,110],"legislative_initiative":[185],"document_type":[],"acf":[],"author_meta":{"display_name":"Miriam Eisermann","author_link":"https:\/\/energy-cities.eu\/fr\/staff\/m-eisermann\/"},"featured_img":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2020\/06\/john-towner-UO02gAW3c0c-unsplash-350x233.jpg","featured_image_src":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2020\/06\/john-towner-UO02gAW3c0c-unsplash.jpg","author_info":{"display_name":"Miriam Eisermann","author_link":"https:\/\/energy-cities.eu\/fr\/staff\/m-eisermann\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La r\u00e9novation \u00e9nerg\u00e9tique dans le plan de relance fran\u00e7ais - Energy Cities<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/energy-cities.eu\/fr\/la-renovation-energetique-dans-le-plan-de-relance-francais\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La r\u00e9novation \u00e9nerg\u00e9tique dans le plan de relance fran\u00e7ais - Energy Cities\" \/>\n<meta property=\"og:description\" content=\"Alors que les propositions fran\u00e7aises de plans de relance abondent, il s\u2019agit d\u00e9sormais d\u2019identifier les leviers les plus efficaces permettant de combiner reprise \u00e9conomique et mont\u00e9e en puissance du march\u00e9 de la r\u00e9novation globale et performante, condition indispensable pour se placer sur une trajectoire convergente avec la strat\u00e9gie nationale bas-carbone fran\u00e7aise.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/energy-cities.eu\/fr\/la-renovation-energetique-dans-le-plan-de-relance-francais\/\" \/>\n<meta property=\"og:site_name\" content=\"Energy Cities\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/energycities.eu\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-29T14:19:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-16T12:29:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/energy-cities.eu\/wp-content\/uploads\/2020\/06\/john-towner-UO02gAW3c0c-unsplash.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2400\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@atonofnews\" \/>\n<meta name=\"twitter:site\" content=\"@energycities\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Miriam Eisermann\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/#organization\",\"name\":\"Energy Cities\",\"url\":\"https:\/\/energy-cities.eu\/fr\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/energycities.eu\/\",\"https:\/\/www.youtube.com\/channel\/UChIHn2wF76JzuTbAjSMs0hQ\",\"https:\/\/fr.wikipedia.org\/wiki\/Energy_Cities\",\"https:\/\/twitter.com\/energycities\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/energy-cities.eu\/wp-content\/uploads\/2019\/07\/energy-cities-couleur.jpg\",\"contentUrl\":\"https:\/\/energy-cities.eu\/wp-content\/uploads\/2019\/07\/energy-cities-couleur.jpg\",\"width\":3508,\"height\":2587,\"caption\":\"Energy Cities\"},\"image\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/#website\",\"url\":\"https:\/\/energy-cities.eu\/fr\/\",\"name\":\"Energy Cities\",\"description\":\" The European learning community for future-proof cities\",\"publisher\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/energy-cities.eu\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/la-renovation-energetique-dans-le-plan-de-relance-francais\/#primaryimage\",\"url\":\"https:\/\/energy-cities.eu\/wp-content\/uploads\/2020\/06\/john-towner-UO02gAW3c0c-unsplash.jpg\",\"contentUrl\":\"https:\/\/energy-cities.eu\/wp-content\/uploads\/2020\/06\/john-towner-UO02gAW3c0c-unsplash.jpg\",\"width\":2400,\"height\":1600,\"caption\":\"John Towner on Unsplash\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/la-renovation-energetique-dans-le-plan-de-relance-francais\/#webpage\",\"url\":\"https:\/\/energy-cities.eu\/fr\/la-renovation-energetique-dans-le-plan-de-relance-francais\/\",\"name\":\"La r\u00e9novation \u00e9nerg\u00e9tique dans le plan de relance fran\u00e7ais - Energy Cities\",\"isPartOf\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/la-renovation-energetique-dans-le-plan-de-relance-francais\/#primaryimage\"},\"datePublished\":\"2020-06-29T14:19:18+00:00\",\"dateModified\":\"2020-07-16T12:29:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/la-renovation-energetique-dans-le-plan-de-relance-francais\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/energy-cities.eu\/fr\/la-renovation-energetique-dans-le-plan-de-relance-francais\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/la-renovation-energetique-dans-le-plan-de-relance-francais\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/energy-cities.eu\/fr\/nous-sommes-un-reseau-europeen-blabla\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La r\u00e9novation \u00e9nerg\u00e9tique dans le plan de relance fran\u00e7ais\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/la-renovation-energetique-dans-le-plan-de-relance-francais\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/la-renovation-energetique-dans-le-plan-de-relance-francais\/#webpage\"},\"author\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/#\/schema\/person\/3340a219cf35746901977e3cb1dc791a\"},\"headline\":\"La r\u00e9novation \u00e9nerg\u00e9tique dans le plan de relance fran\u00e7ais\",\"datePublished\":\"2020-06-29T14:19:18+00:00\",\"dateModified\":\"2020-07-16T12:29:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/la-renovation-energetique-dans-le-plan-de-relance-francais\/#webpage\"},\"wordCount\":1973,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/la-renovation-energetique-dans-le-plan-de-relance-francais\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/energy-cities.eu\/wp-content\/uploads\/2020\/06\/john-towner-UO02gAW3c0c-unsplash.jpg\",\"articleSection\":[\"Actualit\u00e9s\",\"Politique de l'Union Europ\u00e9enne\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/energy-cities.eu\/fr\/la-renovation-energetique-dans-le-plan-de-relance-francais\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/#\/schema\/person\/3340a219cf35746901977e3cb1dc791a\",\"name\":\"Miriam Eisermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f1d254f33ec08630330aef416f9899c3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f1d254f33ec08630330aef416f9899c3?s=96&d=mm&r=g\",\"caption\":\"Miriam Eisermann\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/miriam-eisermann-82507377\/\",\"https:\/\/twitter.com\/atonofnews\"],\"url\":\"https:\/\/energy-cities.eu\/fr\/staff\/m-eisermann\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La r\u00e9novation \u00e9nerg\u00e9tique dans le plan de relance fran\u00e7ais - Energy Cities","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/energy-cities.eu\/fr\/la-renovation-energetique-dans-le-plan-de-relance-francais\/","og_locale":"fr_FR","og_type":"article","og_title":"La r\u00e9novation \u00e9nerg\u00e9tique dans le plan de relance fran\u00e7ais - Energy Cities","og_description":"Alors que les propositions fran\u00e7aises de plans de relance abondent, il s\u2019agit d\u00e9sormais d\u2019identifier les leviers les plus efficaces permettant de combiner reprise \u00e9conomique et mont\u00e9e en puissance du march\u00e9 de la r\u00e9novation globale et performante, condition indispensable pour se placer sur une trajectoire convergente avec la strat\u00e9gie nationale bas-carbone fran\u00e7aise.","og_url":"https:\/\/energy-cities.eu\/fr\/la-renovation-energetique-dans-le-plan-de-relance-francais\/","og_site_name":"Energy Cities","article_publisher":"https:\/\/www.facebook.com\/energycities.eu\/","article_published_time":"2020-06-29T14:19:18+00:00","article_modified_time":"2020-07-16T12:29:56+00:00","og_image":[{"width":2400,"height":1600,"url":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2020\/06\/john-towner-UO02gAW3c0c-unsplash.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@atonofnews","twitter_site":"@energycities","twitter_misc":{"\u00c9crit par":"Miriam Eisermann","Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/energy-cities.eu\/fr\/#organization","name":"Energy Cities","url":"https:\/\/energy-cities.eu\/fr\/","sameAs":["https:\/\/www.facebook.com\/energycities.eu\/","https:\/\/www.youtube.com\/channel\/UChIHn2wF76JzuTbAjSMs0hQ","https:\/\/fr.wikipedia.org\/wiki\/Energy_Cities","https:\/\/twitter.com\/energycities"],"logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/energy-cities.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2019\/07\/energy-cities-couleur.jpg","contentUrl":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2019\/07\/energy-cities-couleur.jpg","width":3508,"height":2587,"caption":"Energy Cities"},"image":{"@id":"https:\/\/energy-cities.eu\/fr\/#\/schema\/logo\/image\/"}},{"@type":"WebSite","@id":"https:\/\/energy-cities.eu\/fr\/#website","url":"https:\/\/energy-cities.eu\/fr\/","name":"Energy Cities","description":" The European learning community for future-proof cities","publisher":{"@id":"https:\/\/energy-cities.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/energy-cities.eu\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/energy-cities.eu\/fr\/la-renovation-energetique-dans-le-plan-de-relance-francais\/#primaryimage","url":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2020\/06\/john-towner-UO02gAW3c0c-unsplash.jpg","contentUrl":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2020\/06\/john-towner-UO02gAW3c0c-unsplash.jpg","width":2400,"height":1600,"caption":"John Towner on Unsplash"},{"@type":"WebPage","@id":"https:\/\/energy-cities.eu\/fr\/la-renovation-energetique-dans-le-plan-de-relance-francais\/#webpage","url":"https:\/\/energy-cities.eu\/fr\/la-renovation-energetique-dans-le-plan-de-relance-francais\/","name":"La r\u00e9novation \u00e9nerg\u00e9tique dans le plan de relance fran\u00e7ais - Energy Cities","isPartOf":{"@id":"https:\/\/energy-cities.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/energy-cities.eu\/fr\/la-renovation-energetique-dans-le-plan-de-relance-francais\/#primaryimage"},"datePublished":"2020-06-29T14:19:18+00:00","dateModified":"2020-07-16T12:29:56+00:00","breadcrumb":{"@id":"https:\/\/energy-cities.eu\/fr\/la-renovation-energetique-dans-le-plan-de-relance-francais\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/energy-cities.eu\/fr\/la-renovation-energetique-dans-le-plan-de-relance-francais\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/energy-cities.eu\/fr\/la-renovation-energetique-dans-le-plan-de-relance-francais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/energy-cities.eu\/fr\/nous-sommes-un-reseau-europeen-blabla\/"},{"@type":"ListItem","position":2,"name":"La r\u00e9novation \u00e9nerg\u00e9tique dans le plan de relance fran\u00e7ais"}]},{"@type":"Article","@id":"https:\/\/energy-cities.eu\/fr\/la-renovation-energetique-dans-le-plan-de-relance-francais\/#article","isPartOf":{"@id":"https:\/\/energy-cities.eu\/fr\/la-renovation-energetique-dans-le-plan-de-relance-francais\/#webpage"},"author":{"@id":"https:\/\/energy-cities.eu\/fr\/#\/schema\/person\/3340a219cf35746901977e3cb1dc791a"},"headline":"La r\u00e9novation \u00e9nerg\u00e9tique dans le plan de relance fran\u00e7ais","datePublished":"2020-06-29T14:19:18+00:00","dateModified":"2020-07-16T12:29:56+00:00","mainEntityOfPage":{"@id":"https:\/\/energy-cities.eu\/fr\/la-renovation-energetique-dans-le-plan-de-relance-francais\/#webpage"},"wordCount":1973,"commentCount":0,"publisher":{"@id":"https:\/\/energy-cities.eu\/fr\/#organization"},"image":{"@id":"https:\/\/energy-cities.eu\/fr\/la-renovation-energetique-dans-le-plan-de-relance-francais\/#primaryimage"},"thumbnailUrl":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2020\/06\/john-towner-UO02gAW3c0c-unsplash.jpg","articleSection":["Actualit\u00e9s","Politique de l'Union Europ\u00e9enne"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/energy-cities.eu\/fr\/la-renovation-energetique-dans-le-plan-de-relance-francais\/#respond"]}]},{"@type":"Person","@id":"https:\/\/energy-cities.eu\/fr\/#\/schema\/person\/3340a219cf35746901977e3cb1dc791a","name":"Miriam Eisermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/energy-cities.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f1d254f33ec08630330aef416f9899c3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f1d254f33ec08630330aef416f9899c3?s=96&d=mm&r=g","caption":"Miriam Eisermann"},"sameAs":["https:\/\/www.linkedin.com\/in\/miriam-eisermann-82507377\/","https:\/\/twitter.com\/atonofnews"],"url":"https:\/\/energy-cities.eu\/fr\/staff\/m-eisermann\/"}]}},"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/energy-cities.eu\/fr\/category\/actualites\/\" class=\"advgb-post-tax-term\">Actualit\u00e9s<\/a>","<a href=\"https:\/\/energy-cities.eu\/fr\/category\/politique-de-lunion-europeenne\/\" class=\"advgb-post-tax-term\">Politique de l&#039;Union Europ\u00e9enne<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Actualit\u00e9s<\/span>","<span class=\"advgb-post-tax-term\">Politique de l&#039;Union Europ\u00e9enne<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publi\u00e9 6 ans il y a","modified":"Mis \u00e0 jour 6 ans il y a"},"absolute_dates":{"created":"Publi\u00e9 le 29 juin 2020","modified":"Mise \u00e0 jour le 16 juillet 2020"},"absolute_dates_time":{"created":"Publi\u00e9 le 29 juin 2020 4:19  ","modified":"Mise \u00e0 jour le 16 juillet 2020 2:29  "},"featured_img_caption":"John Towner on Unsplash","_links":{"self":[{"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/posts\/32245"}],"collection":[{"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/comments?post=32245"}],"version-history":[{"count":6,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/posts\/32245\/revisions"}],"predecessor-version":[{"id":32258,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/posts\/32245\/revisions\/32258"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/media\/32241"}],"wp:attachment":[{"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/media?parent=32245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/categories?post=32245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/tags?post=32245"},{"taxonomy":"hub","embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/hub?post=32245"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/topic?post=32245"},{"taxonomy":"legislative_initiative","embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/legislative_initiative?post=32245"},{"taxonomy":"document_type","embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/document_type?post=32245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}