{"id":9067,"date":"2016-06-28T14:09:03","date_gmt":"2016-06-28T14:09:03","guid":{"rendered":"http:\/\/ec.kuusi.ovh\/?p=9067"},"modified":"2019-01-14T17:39:27","modified_gmt":"2019-01-14T17:39:27","slug":"lunion-de-lenergie-a-cruellement-besoin-dune-revolution-par-le-bas","status":"publish","type":"post","link":"https:\/\/energy-cities.eu\/fr\/lunion-de-lenergie-a-cruellement-besoin-dune-revolution-par-le-bas\/","title":{"rendered":"L&rsquo;UNION DE L&rsquo;\u00c9NERGIE A CRUELLEMENT BESOIN D&rsquo;UNE \u00ab\u00a0R\u00c9VOLUTION PAR LE BAS\u00a0\u00bb"},"content":{"rendered":"\n<p>En Italie, les experts parlent de l\u2019\u00e9mergence d\u2019une \u00ab\u00a0r\u00e9volution par le bas\u00a0\u00bb, port\u00e9e par les autorit\u00e9s locales qui ont aid\u00e9 le pays \u00e0 augmenter la part des \u00e9nergies renouvelables de 15% \u00e0 35,5% en seulement quelques ann\u00e9es, avec d\u2019\u00e9normes b\u00e9n\u00e9fices socio-\u00e9conomiques.<br>Au niveau europ\u00e9en, cette r\u00e9volution et le r\u00f4le que les autorit\u00e9s locales y jouent, est le plus souvent limit\u00e9e \u00e0 des programmes en marge et initiatives sp\u00e9cifiques comme la Convention des Maires et l\u2019Agenda Urbain.<br>Bien qu\u2019il soit important que les villes soient soutenues via des m\u00e9canismes cibl\u00e9s pour faire avancer la transition \u00e9nerg\u00e9tique, il est \u00e9galement crucial que leurs propres priorit\u00e9s et contributions trouvent un \u00e9cho dans les forts enjeux politiques europ\u00e9ens existants tels que le plan strat\u00e9gique de la construction d\u2019une Union de l\u2019\u00c9nergie.<br><\/p>\n\n\n\n<p>Au cours de cet \u00e9t\u00e9, la Commission europ\u00e9enne pr\u00e9voit d\u2019\u00e9toffer sa proposition pour la&nbsp;<a href=\"http:\/\/www.consilium.europa.eu\/fr\/press\/press-releases\/2015\/11\/26-conclusions-energy-union-governance\/\">gouvernance de l\u2019Union de l\u2019\u00c9nergie.<\/a>&nbsp;Malheureusement, les premi\u00e8res versions et documents entourant cet exercice montrent que la dimension locale est sensiblement absente des discussions &#8230;<\/p>\n\n\n\n<p>En effet, alors que l\u2019ex\u00e9cutif europ\u00e9en met beaucoup d\u2019efforts \u00e0 inciter les \u00c9tats membres \u00e0 coop\u00e9rer entre eux et \u00e0 cr\u00e9er un march\u00e9 commun de l\u2019\u00e9nergie, \u00e0 aucun moment il ne pr\u00e9voit d\u2019orienter la fa\u00e7on dont les autorit\u00e9s locales participent, parmi lesquelles 7000 ont adopt\u00e9 volontairement des plans d\u2019action \u00e9nergie pr\u00e9vus dans la&nbsp;<a href=\"http:\/\/www.conventiondesmaires.eu\/index_fr.html\">Convention des maires<\/a>.&nbsp;<strong>Pour combler cette lacune, Energy Cities a travaill\u00e9 sur<\/strong>&nbsp;<a href=\"http:\/\/www.energy-cities.eu\/IMG\/pdf\/guidance_paper_to_ms_energy_union_governance_final_draft.pdf\"><strong>un projet de ce \u00e0 quoi un tel document d\u2019orientation pourrait ressembler<\/strong><\/a>&nbsp;<em>(en anglais)<\/em>,&nbsp;<strong>et l\u2019a envoy\u00e9 comme source d\u2019inspiration aux d\u00e9cideurs cl\u00e9s de la Commission europ\u00e9enne et du Parlement<\/strong>.<\/p>\n\n\n\n<p>En un mot, le document explique le potentiel local des \u00e9conomies et des \u00e9nergies renouvelables qui est pens\u00e9 dans les plans nationaux \u00c9nergie et Climat qui formeront l\u2019\u00e9pine dorsale du cadre 2030.<\/p>\n\n\n\n<p>La Commission europ\u00e9enne se soucie toujours de la n\u00e9cessit\u00e9 d\u2019une diversification. Mais au-del\u00e0 de l\u2019envie de changer simplement de fournisseurs (de la Russie aux pays de la mer Caspienne, par exemple), il est peut-\u00eatre temps de regarder la diversification dans le sens de compter de plus en plus de sources d\u2019\u00e9nergies locales et r\u00e9silientes. Comme la l\u00e9gitimit\u00e9 de l\u2019UE est au plus bas, cette approche locale contribuera \u00e9galement \u00e0 la coh\u00e9sion sociale et territoriale bien n\u00e9cessaire qui \u00e9tait autrefois promis aux citoyens europ\u00e9ens.<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Italie, les experts parlent de l\u2019\u00e9mergence d\u2019une \u00ab\u00a0r\u00e9volution par le bas\u00a0\u00bb, port\u00e9e par les autorit\u00e9s locales qui ont aid\u00e9 le pays \u00e0 augmenter la <a href=\"https:\/\/energy-cities.eu\/fr\/lunion-de-lenergie-a-cruellement-besoin-dune-revolution-par-le-bas\/\">[\u2026]<\/a><\/p>\n","protected":false},"author":26,"featured_media":15852,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","ub_ctt_via":""},"categories":[4],"tags":[],"hub":[],"topic":[22],"legislative_initiative":[],"document_type":[],"acf":[],"author_meta":{"display_name":"Alix Bolle","author_link":"https:\/\/energy-cities.eu\/fr\/staff\/a-bolle\/"},"featured_img":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2019\/05\/world-1264062_theAndras-Barta_pixabay-300x200.jpg","featured_image_src":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2019\/05\/world-1264062_theAndras-Barta_pixabay.jpg","author_info":{"display_name":"Alix Bolle","author_link":"https:\/\/energy-cities.eu\/fr\/staff\/a-bolle\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L&#039;UNION DE L&#039;\u00c9NERGIE A CRUELLEMENT BESOIN D&#039;UNE &quot;R\u00c9VOLUTION PAR LE BAS&quot; - Energy Cities<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/energy-cities.eu\/fr\/lunion-de-lenergie-a-cruellement-besoin-dune-revolution-par-le-bas\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;UNION DE L&#039;\u00c9NERGIE A CRUELLEMENT BESOIN D&#039;UNE &quot;R\u00c9VOLUTION PAR LE BAS&quot; - Energy Cities\" \/>\n<meta property=\"og:description\" content=\"En Italie, les experts parlent de l\u2019\u00e9mergence d\u2019une \u00ab\u00a0r\u00e9volution par le bas\u00a0\u00bb, port\u00e9e par les autorit\u00e9s locales qui ont aid\u00e9 le pays \u00e0 augmenter la [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/energy-cities.eu\/fr\/lunion-de-lenergie-a-cruellement-besoin-dune-revolution-par-le-bas\/\" \/>\n<meta property=\"og:site_name\" content=\"Energy Cities\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/energycities.eu\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-28T14:09:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-14T17:39:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/energy-cities.eu\/wp-content\/uploads\/2019\/05\/world-1264062_theAndras-Barta_pixabay-1024x683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@b.karas\" \/>\n<meta name=\"twitter:site\" content=\"@energycities\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alix Bolle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/#organization\",\"name\":\"Energy Cities\",\"url\":\"https:\/\/energy-cities.eu\/fr\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/energycities.eu\/\",\"https:\/\/www.youtube.com\/channel\/UChIHn2wF76JzuTbAjSMs0hQ\",\"https:\/\/fr.wikipedia.org\/wiki\/Energy_Cities\",\"https:\/\/twitter.com\/energycities\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/energy-cities.eu\/wp-content\/uploads\/2019\/07\/energy-cities-couleur.jpg\",\"contentUrl\":\"https:\/\/energy-cities.eu\/wp-content\/uploads\/2019\/07\/energy-cities-couleur.jpg\",\"width\":3508,\"height\":2587,\"caption\":\"Energy Cities\"},\"image\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/#website\",\"url\":\"https:\/\/energy-cities.eu\/fr\/\",\"name\":\"Energy Cities\",\"description\":\" The European learning community for future-proof cities\",\"publisher\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/energy-cities.eu\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/lunion-de-lenergie-a-cruellement-besoin-dune-revolution-par-le-bas\/#primaryimage\",\"url\":\"https:\/\/energy-cities.eu\/wp-content\/uploads\/2019\/05\/world-1264062_theAndras-Barta_pixabay.jpg\",\"contentUrl\":\"https:\/\/energy-cities.eu\/wp-content\/uploads\/2019\/05\/world-1264062_theAndras-Barta_pixabay.jpg\",\"width\":4592,\"height\":3064,\"caption\":\"\u00a9 1264062_theAndras Barta_pixabay\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/lunion-de-lenergie-a-cruellement-besoin-dune-revolution-par-le-bas\/#webpage\",\"url\":\"https:\/\/energy-cities.eu\/fr\/lunion-de-lenergie-a-cruellement-besoin-dune-revolution-par-le-bas\/\",\"name\":\"L'UNION DE L'\u00c9NERGIE A CRUELLEMENT BESOIN D'UNE \\\"R\u00c9VOLUTION PAR LE BAS\\\" - Energy Cities\",\"isPartOf\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/lunion-de-lenergie-a-cruellement-besoin-dune-revolution-par-le-bas\/#primaryimage\"},\"datePublished\":\"2016-06-28T14:09:03+00:00\",\"dateModified\":\"2019-01-14T17:39:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/lunion-de-lenergie-a-cruellement-besoin-dune-revolution-par-le-bas\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/energy-cities.eu\/fr\/lunion-de-lenergie-a-cruellement-besoin-dune-revolution-par-le-bas\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/lunion-de-lenergie-a-cruellement-besoin-dune-revolution-par-le-bas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/energy-cities.eu\/fr\/nous-sommes-un-reseau-europeen-blabla\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;UNION DE L&#8217;\u00c9NERGIE A CRUELLEMENT BESOIN D&#8217;UNE &#8220;R\u00c9VOLUTION PAR LE BAS&#8221;\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/lunion-de-lenergie-a-cruellement-besoin-dune-revolution-par-le-bas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/lunion-de-lenergie-a-cruellement-besoin-dune-revolution-par-le-bas\/#webpage\"},\"author\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/#\/schema\/person\/539fc4eb5dc93bd9d774c71b93f22163\"},\"headline\":\"L&rsquo;UNION DE L&rsquo;\u00c9NERGIE A CRUELLEMENT BESOIN D&rsquo;UNE \u00ab\u00a0R\u00c9VOLUTION PAR LE BAS\u00a0\u00bb\",\"datePublished\":\"2016-06-28T14:09:03+00:00\",\"dateModified\":\"2019-01-14T17:39:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/lunion-de-lenergie-a-cruellement-besoin-dune-revolution-par-le-bas\/#webpage\"},\"wordCount\":446,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/lunion-de-lenergie-a-cruellement-besoin-dune-revolution-par-le-bas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/energy-cities.eu\/wp-content\/uploads\/2019\/05\/world-1264062_theAndras-Barta_pixabay.jpg\",\"articleSection\":[\"Actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/energy-cities.eu\/fr\/lunion-de-lenergie-a-cruellement-besoin-dune-revolution-par-le-bas\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/#\/schema\/person\/539fc4eb5dc93bd9d774c71b93f22163\",\"name\":\"Alix Bolle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ac82c648bc514c4b7626ff56c37d6a27?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ac82c648bc514c4b7626ff56c37d6a27?s=96&d=mm&r=g\",\"caption\":\"Alix Bolle\"},\"sameAs\":[\"https:\/\/twitter.com\/b.karas\"],\"url\":\"https:\/\/energy-cities.eu\/fr\/staff\/a-bolle\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'UNION DE L'\u00c9NERGIE A CRUELLEMENT BESOIN D'UNE \"R\u00c9VOLUTION PAR LE BAS\" - Energy Cities","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/energy-cities.eu\/fr\/lunion-de-lenergie-a-cruellement-besoin-dune-revolution-par-le-bas\/","og_locale":"fr_FR","og_type":"article","og_title":"L'UNION DE L'\u00c9NERGIE A CRUELLEMENT BESOIN D'UNE \"R\u00c9VOLUTION PAR LE BAS\" - Energy Cities","og_description":"En Italie, les experts parlent de l\u2019\u00e9mergence d\u2019une \u00ab\u00a0r\u00e9volution par le bas\u00a0\u00bb, port\u00e9e par les autorit\u00e9s locales qui ont aid\u00e9 le pays \u00e0 augmenter la [\u2026]","og_url":"https:\/\/energy-cities.eu\/fr\/lunion-de-lenergie-a-cruellement-besoin-dune-revolution-par-le-bas\/","og_site_name":"Energy Cities","article_publisher":"https:\/\/www.facebook.com\/energycities.eu\/","article_published_time":"2016-06-28T14:09:03+00:00","article_modified_time":"2019-01-14T17:39:27+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2019\/05\/world-1264062_theAndras-Barta_pixabay-1024x683.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@b.karas","twitter_site":"@energycities","twitter_misc":{"\u00c9crit par":"Alix Bolle","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/energy-cities.eu\/fr\/#organization","name":"Energy Cities","url":"https:\/\/energy-cities.eu\/fr\/","sameAs":["https:\/\/www.facebook.com\/energycities.eu\/","https:\/\/www.youtube.com\/channel\/UChIHn2wF76JzuTbAjSMs0hQ","https:\/\/fr.wikipedia.org\/wiki\/Energy_Cities","https:\/\/twitter.com\/energycities"],"logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/energy-cities.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2019\/07\/energy-cities-couleur.jpg","contentUrl":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2019\/07\/energy-cities-couleur.jpg","width":3508,"height":2587,"caption":"Energy Cities"},"image":{"@id":"https:\/\/energy-cities.eu\/fr\/#\/schema\/logo\/image\/"}},{"@type":"WebSite","@id":"https:\/\/energy-cities.eu\/fr\/#website","url":"https:\/\/energy-cities.eu\/fr\/","name":"Energy Cities","description":" The European learning community for future-proof cities","publisher":{"@id":"https:\/\/energy-cities.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/energy-cities.eu\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/energy-cities.eu\/fr\/lunion-de-lenergie-a-cruellement-besoin-dune-revolution-par-le-bas\/#primaryimage","url":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2019\/05\/world-1264062_theAndras-Barta_pixabay.jpg","contentUrl":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2019\/05\/world-1264062_theAndras-Barta_pixabay.jpg","width":4592,"height":3064,"caption":"\u00a9 1264062_theAndras Barta_pixabay"},{"@type":"WebPage","@id":"https:\/\/energy-cities.eu\/fr\/lunion-de-lenergie-a-cruellement-besoin-dune-revolution-par-le-bas\/#webpage","url":"https:\/\/energy-cities.eu\/fr\/lunion-de-lenergie-a-cruellement-besoin-dune-revolution-par-le-bas\/","name":"L'UNION DE L'\u00c9NERGIE A CRUELLEMENT BESOIN D'UNE \"R\u00c9VOLUTION PAR LE BAS\" - Energy Cities","isPartOf":{"@id":"https:\/\/energy-cities.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/energy-cities.eu\/fr\/lunion-de-lenergie-a-cruellement-besoin-dune-revolution-par-le-bas\/#primaryimage"},"datePublished":"2016-06-28T14:09:03+00:00","dateModified":"2019-01-14T17:39:27+00:00","breadcrumb":{"@id":"https:\/\/energy-cities.eu\/fr\/lunion-de-lenergie-a-cruellement-besoin-dune-revolution-par-le-bas\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/energy-cities.eu\/fr\/lunion-de-lenergie-a-cruellement-besoin-dune-revolution-par-le-bas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/energy-cities.eu\/fr\/lunion-de-lenergie-a-cruellement-besoin-dune-revolution-par-le-bas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/energy-cities.eu\/fr\/nous-sommes-un-reseau-europeen-blabla\/"},{"@type":"ListItem","position":2,"name":"L&#8217;UNION DE L&#8217;\u00c9NERGIE A CRUELLEMENT BESOIN D&#8217;UNE &#8220;R\u00c9VOLUTION PAR LE BAS&#8221;"}]},{"@type":"Article","@id":"https:\/\/energy-cities.eu\/fr\/lunion-de-lenergie-a-cruellement-besoin-dune-revolution-par-le-bas\/#article","isPartOf":{"@id":"https:\/\/energy-cities.eu\/fr\/lunion-de-lenergie-a-cruellement-besoin-dune-revolution-par-le-bas\/#webpage"},"author":{"@id":"https:\/\/energy-cities.eu\/fr\/#\/schema\/person\/539fc4eb5dc93bd9d774c71b93f22163"},"headline":"L&rsquo;UNION DE L&rsquo;\u00c9NERGIE A CRUELLEMENT BESOIN D&rsquo;UNE \u00ab\u00a0R\u00c9VOLUTION PAR LE BAS\u00a0\u00bb","datePublished":"2016-06-28T14:09:03+00:00","dateModified":"2019-01-14T17:39:27+00:00","mainEntityOfPage":{"@id":"https:\/\/energy-cities.eu\/fr\/lunion-de-lenergie-a-cruellement-besoin-dune-revolution-par-le-bas\/#webpage"},"wordCount":446,"commentCount":0,"publisher":{"@id":"https:\/\/energy-cities.eu\/fr\/#organization"},"image":{"@id":"https:\/\/energy-cities.eu\/fr\/lunion-de-lenergie-a-cruellement-besoin-dune-revolution-par-le-bas\/#primaryimage"},"thumbnailUrl":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2019\/05\/world-1264062_theAndras-Barta_pixabay.jpg","articleSection":["Actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/energy-cities.eu\/fr\/lunion-de-lenergie-a-cruellement-besoin-dune-revolution-par-le-bas\/#respond"]}]},{"@type":"Person","@id":"https:\/\/energy-cities.eu\/fr\/#\/schema\/person\/539fc4eb5dc93bd9d774c71b93f22163","name":"Alix Bolle","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/energy-cities.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ac82c648bc514c4b7626ff56c37d6a27?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ac82c648bc514c4b7626ff56c37d6a27?s=96&d=mm&r=g","caption":"Alix Bolle"},"sameAs":["https:\/\/twitter.com\/b.karas"],"url":"https:\/\/energy-cities.eu\/fr\/staff\/a-bolle\/"}]}},"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/energy-cities.eu\/fr\/category\/actualites\/\" class=\"advgb-post-tax-term\">Actualit\u00e9s<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Actualit\u00e9s<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publi\u00e9 10 ans il y a","modified":"Mis \u00e0 jour 8 ans il y a"},"absolute_dates":{"created":"Publi\u00e9 le 28 juin 2016","modified":"Mise \u00e0 jour le 14 janvier 2019"},"absolute_dates_time":{"created":"Publi\u00e9 le 28 juin 2016 2:09  ","modified":"Mise \u00e0 jour le 14 janvier 2019 5:39  "},"featured_img_caption":"\u00a9 1264062_theAndras Barta_pixabay","_links":{"self":[{"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/posts\/9067"}],"collection":[{"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/comments?post=9067"}],"version-history":[{"count":3,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/posts\/9067\/revisions"}],"predecessor-version":[{"id":10988,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/posts\/9067\/revisions\/10988"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/media\/15852"}],"wp:attachment":[{"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/media?parent=9067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/categories?post=9067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/tags?post=9067"},{"taxonomy":"hub","embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/hub?post=9067"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/topic?post=9067"},{"taxonomy":"legislative_initiative","embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/legislative_initiative?post=9067"},{"taxonomy":"document_type","embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/document_type?post=9067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}