{"id":91005,"date":"2025-10-17T16:47:51","date_gmt":"2025-10-17T14:47:51","guid":{"rendered":"https:\/\/energy-cities.eu\/?p=91005"},"modified":"2025-10-17T16:49:29","modified_gmt":"2025-10-17T14:49:29","slug":"manque-delan-national-pour-la-planification-local-du-chauffage-et-du-refroidissement","status":"publish","type":"post","link":"https:\/\/energy-cities.eu\/fr\/manque-delan-national-pour-la-planification-local-du-chauffage-et-du-refroidissement\/","title":{"rendered":"Manque d&rsquo;\u00e9lan national pour la planification local du chauffage et du refroidissement"},"content":{"rendered":"\n<p>En octobre 2023, la nouvelle version de la <a href=\"https:\/\/energy.ec.europa.eu\/topics\/energy-efficiency\/energy-efficiency-targets-directive-and-rules\/energy-efficiency-directive_en\" target=\"_blank\" rel=\"noreferrer noopener\">directive sur l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique (DEE)<\/a> a \u00e9t\u00e9 publi\u00e9e au Journal officiel de l\u2019Union europ\u00e9enne. Depuis, les \u00c9tats membres ont \u00e9t\u00e9 charg\u00e9s de transposer ses dispositions dans leur droit national \u2013 et le d\u00e9lai est d\u00e9j\u00e0 d\u00e9pass\u00e9.<\/p>\n\n\n\n<p>Selon le calendrier fix\u00e9 par la directive, l\u2019article 25.6 sur la planification locale du chauffage et du refroidissement doit \u00eatre transpos\u00e9 dans les l\u00e9gislations nationales d\u2019ici le 11 octobre 2025. Concr\u00e8tement, tous les \u00c9tats membres doivent mettre en place un cadre juridique obligeant les municipalit\u00e9s de plus de 45 000 habitants \u00e0 planifier la d\u00e9carbonation de leurs syst\u00e8mes de chauffage et de refroidissement.<\/p>\n\n\n\n<p>Deux ans apr\u00e8s la publication de la directive, Energy Cities a mis \u00e0 jour son outil de suivi&nbsp;<strong><a href=\"https:\/\/energy-cities.eu\/local-heating-and-cooling-plan\/\" target=\"_blank\" rel=\"noreferrer noopener\">EU Tracker<\/a><\/strong>, qui \u00e9value la pr\u00e9paration des \u00c9tats membres \u00e0 appliquer l\u2019article 25.6. Cette ann\u00e9e, le suivi s\u2019est concentr\u00e9 sur la transposition juridique, tout en gardant un \u0153il sur les mesures qui peuvent transformer les obligations de planification en v\u00e9ritables actions locales.<\/p>\n\n\n\n<p>Les r\u00e9sultats sont mitig\u00e9s :<\/p>\n\n\n\n<ul><li>8 \u00c9tats membres ont transpos\u00e9 l\u2019article 25.6 ou disposent d\u00e9j\u00e0 d\u2019un cadre juridique adapt\u00e9 (France, Allemagne, Pays-Bas, Danemark, Croatie, Hongrie, Estonie, Finlande)<\/li><li>9 \u00c9tats membres pr\u00e9sentent encore de s\u00e9rieuses lacunes (Portugal, Espagne, Italie, Bulgarie, Roumanie, Pologne, Slovaquie, Lituanie)<\/li><li>et 19 \u00c9tats membres ont manqu\u00e9 le d\u00e9lai de transposition.<\/li><\/ul>\n\n\n\n<p>La c\u00e9l\u00e9bration attendra encore un peu.<\/p>\n\n\n\n<h2>Les \u00c9tats membres ne prennent pas le d\u00e9fi au s\u00e9rieux<\/h2>\n\n\n\n<p>Certains pays, comme les Pays-Bas et le Danemark, ont montr\u00e9 une certaine avance, et&nbsp;<strong>l\u2019Allemagne<\/strong>&nbsp;a \u00e9t\u00e9 la premi\u00e8re \u00e0 transposer officiellement la directive. <a href=\"https:\/\/energy-cities.eu\/fr\/lallemagne-adopte-une-loi-en-faveur-de-la-planification-de-la-chaleur-et-du-froid-au-niveau-local%EF%BF%BC\/\" target=\"_blank\" rel=\"noreferrer noopener\">Energy Cities avait salu\u00e9<\/a> cette avanc\u00e9e en 2024. Mais l\u2019arriv\u00e9e d\u2019un nouveau gouvernement f\u00e9d\u00e9ral a vite refroidi l\u2019enthousiasme : la loi sur le chauffage, r\u00e9cemment adopt\u00e9e, a \u00e9t\u00e9 la cible de d\u00e9sinformation et les d\u00e9bats politiques ont remis en question son ambition. Une situation qui se r\u00e9p\u00e8te ailleurs en Europe.<\/p>\n\n\n\n<p>En&nbsp;<strong>Autriche<\/strong>, le gouvernement f\u00e9d\u00e9ral travaille avec les L\u00e4nder sur une strat\u00e9gie nationale de chauffage et de refroidissement visant la d\u00e9carbonation totale d\u2019ici 2040. Le programme de financement f\u00e9d\u00e9ral, qui couvrait jusqu\u2019\u00e0 75 % du co\u00fbt de remplacement des syst\u00e8mes de chauffage, a pris fin en 2024 et est en cours de r\u00e9vision. Quelques programmes r\u00e9gionaux, comme celui de Vienne, restent cependant actifs.<\/p>\n\n\n\n<p>En&nbsp;<strong>Su\u00e8de<\/strong>, la Commission europ\u00e9enne a engag\u00e9 une proc\u00e9dure d\u2019infraction pour des lacunes dans la mise en \u0153uvre de la directive. Les critiques portent sur le manque de mesures suffisantes pour assurer un suivi r\u00e9gulier de la planification \u00e9nerg\u00e9tique locale. L\u2019article 25.6 n\u2019a pas encore \u00e9t\u00e9 transpos\u00e9. Les municipalit\u00e9s ont exprim\u00e9 leurs inqui\u00e9tudes face au manque de soutien et de ressources pour r\u00e9pondre \u00e0 ces nouvelles exigences. Beaucoup se sentent d\u00e9pass\u00e9es par la charge administrative et financi\u00e8re qu\u2019implique la planification locale du chauffage.<\/p>\n\n\n\n<p>Lors de la transposition de l\u2019article 25.6, la plupart des \u00c9tats membres ont opt\u00e9 pour un niveau d\u2019ambition minimal :<\/p>\n\n\n\n<ul><li>En&nbsp;<strong>France<\/strong>, une partie de l\u2019article a \u00e9t\u00e9 transpos\u00e9e via la loi DDADUE, qui impose l\u2019obligation uniquement aux intercommunalit\u00e9s (EPCI) comprenant au moins une commune de plus de 45 000 habitants \u2014 un seuil moins ambitieux que celui pr\u00e9vu par la directive. Aucun calendrier ni exigence concr\u00e8te de mise en \u0153uvre n\u2019a encore \u00e9t\u00e9 d\u00e9fini. Un d\u00e9cret et un guide d\u2019application sont attendus prochainement.<\/li><li>En&nbsp;<strong>Croatie<\/strong>, la directive a \u00e9t\u00e9 transpos\u00e9e avec des dispositions g\u00e9n\u00e9rales. La derni\u00e8re mise \u00e0 jour de la loi sur le march\u00e9 de la chaleur (avril 2025) impose aux collectivit\u00e9s de plus de 35 000 habitants d\u2019\u00e9laborer des plans de chauffage et de refroidissement. Ce seuil est plus ambitieux que celui exig\u00e9 par la directive, mais il manque un cadre de soutien adapt\u00e9.<\/li><li>En&nbsp;<strong>Espagne<\/strong>, la transposition a fait l\u2019objet d\u2019une large consultation, avec la participation de la soci\u00e9t\u00e9 civile. Un nouveau guide sur le chauffage a \u00e9t\u00e9 publi\u00e9 et servira de base au gouvernement national, mais le cadre de soutien reste inchang\u00e9.<\/li><li>En&nbsp;<strong>Hongrie<\/strong>, la transposition partielle de la directive confie la majorit\u00e9 des responsabilit\u00e9s aux municipalit\u00e9s, sans leur fournir les ressources n\u00e9cessaires. La loi sur les services de chauffage urbain confie cette mission aux conseils municipaux des villes de plus de 45 000 habitants.<\/li><li>En&nbsp;<strong>Flandre<\/strong>&nbsp;(Belgique), un premier projet de transposition a \u00e9t\u00e9 adopt\u00e9, avec une adoption finale pr\u00e9vue autour de novembre. Le texte reprend le seuil de 45 000 habitants. Le gouvernement flamand a toutefois d\u00e9cid\u00e9 de mettre fin au Pacte local pour l\u2019\u00e9nergie et le climat, qui offrait un soutien pr\u00e9cieux aux communes.<\/li><\/ul>\n\n\n\n<p>Des informations d\u00e9taill\u00e9es sur chaque \u00c9tat membre sont disponibles dans les fiches pays de l\u2019<strong><a href=\"https:\/\/energy-cities.eu\/local-heating-and-cooling-plan\/\">EU Tracker<\/a><\/strong>. Vous pouvez \u00e9galement d\u00e9couvrir comment les villes mettent ces politiques en pratique \u00e0 travers les <a href=\"https:\/\/energy-cities.eu\/fr\/comment-les-villes-europeennes-menent-la-transition-vers-un-chauffage-decarbone\/\" target=\"_blank\" rel=\"noreferrer noopener\">histoires inspirantes<\/a> publi\u00e9es par Energy Cities sur la d\u00e9carbonation.<\/p>\n\n\n\n<h2>Et ensuite ?<\/h2>\n\n\n\n<p>La Commission europ\u00e9enne va commencer \u00e0 surveiller la transposition de l\u2019article 25.6 et \u00e0 encourager les \u00c9tats membres \u00e0 se mettre en conformit\u00e9. Ceux qui ne l\u2019auront pas fait s\u2019exposeront \u00e0 une proc\u00e9dure d\u2019infraction.<\/p>\n\n\n\n<p>Parall\u00e8lement, la Commission pr\u00e9pare une&nbsp;<strong>nouvelle strat\u00e9gie europ\u00e9enne pour le chauffage et le refroidissement<\/strong>. Initialement attendue fin 2025, sa publication est d\u00e9sormais pr\u00e9vue d\u00e9but 2026. L\u2019objectif : en faire un v\u00e9ritable outil pour aider les \u00c9tats membres et les municipalit\u00e9s \u00e0 planifier et mettre en \u0153uvre la transition. <a href=\"https:\/\/ec.europa.eu\/info\/law\/better-regulation\/have-your-say\/initiatives\/14818-Energy-Heating-and-Cooling-Strategy_en\" target=\"_blank\" rel=\"noreferrer noopener\">Une consultation publique<\/a> est en cours jusqu\u2019au 20 novembre. <a href=\"https:\/\/energy-cities.eu\/fr\/quoi-de-neuf-dans-lue-les-dernieres-actualites-sur-le-chauffage-et-le-refroidissement\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pour Energy Cities<\/a>, cette strat\u00e9gie doit d\u00e9finir des trajectoires claires de d\u00e9carbonation pour la chaleur industrielle et urbaine, acc\u00e9l\u00e9rer les proc\u00e9dures et stimuler l\u2019investissement dans les technologies propres.<\/p>\n\n\n\n<p>Enfin, Energy Cities suit \u00e9galement les discussions sur le prochain\u00a0<strong>cadre financier pluriannuel (CFP)<\/strong>. La proposition de la Commission pour 2028-2034, pr\u00e9sent\u00e9e le 16 juillet, introduit de nouveaux \u00ab plans de partenariat nationaux et r\u00e9gionaux \u00bb cens\u00e9s simplifier le financement europ\u00e9en. Energy Cities et la Local Alliance estiment toutefois que cette approche risque de centraliser le budget de l\u2019UE, d\u2019affaiblir la politique de coh\u00e9sion et de marginaliser les autorit\u00e9s locales et r\u00e9gionales. Le futur cadre financier pourrait pourtant \u00eatre un levier essentiel pour soutenir les projets de chauffage et de refroidissement durables. La cr\u00e9ation d\u2019un\u00a0<strong>Fonds pour la chaleur propre<\/strong>\u00a0permettrait d\u2019aider les collectivit\u00e9s \u00e0 passer de la planification \u00e0 la mise en \u0153uvre de projets concrets.<\/p>\n\n\n\n<p class=\"light-green-message\" style=\"font-size:17px\">Restez inform\u00e9 sur ce sujet \u2013 <a href=\"https:\/\/energy-cities.eu\/join-energy-cities-hubs\/\" target=\"_blank\" rel=\"noreferrer noopener\">abonnez-vous<\/a> d\u00e8s maintenant \u00e0 notre bulletin HUB 2 !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En octobre 2023, la nouvelle version de la directive sur l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique (DEE) a \u00e9t\u00e9 publi\u00e9e au Journal officiel de l\u2019Union europ\u00e9enne. Depuis, les \u00c9tats <a href=\"https:\/\/energy-cities.eu\/fr\/manque-delan-national-pour-la-planification-local-du-chauffage-et-du-refroidissement\/\">[\u2026]<\/a><\/p>\n","protected":false},"author":83,"featured_media":90685,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","ub_ctt_via":""},"categories":[4],"tags":[],"hub":[308],"topic":[112,332,350,591],"legislative_initiative":[159],"document_type":[],"acf":[],"author_meta":{"display_name":"Nicolas Raimondi","author_link":"https:\/\/energy-cities.eu\/fr\/staff\/n-raimondi\/"},"featured_img":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2025\/10\/AdobeStock_467260138-350x233.jpeg","featured_image_src":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2025\/10\/AdobeStock_467260138-scaled.jpeg","author_info":{"display_name":"Nicolas Raimondi","author_link":"https:\/\/energy-cities.eu\/fr\/staff\/n-raimondi\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Manque d&#039;\u00e9lan national pour la planification local du chauffage et du refroidissement - Energy Cities<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/energy-cities.eu\/fr\/manque-delan-national-pour-la-planification-local-du-chauffage-et-du-refroidissement\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Manque d&#039;\u00e9lan national pour la planification local du chauffage et du refroidissement - Energy Cities\" \/>\n<meta property=\"og:description\" content=\"En octobre 2023, la nouvelle version de la directive sur l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique (DEE) a \u00e9t\u00e9 publi\u00e9e au Journal officiel de l\u2019Union europ\u00e9enne. Depuis, les \u00c9tats [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/energy-cities.eu\/fr\/manque-delan-national-pour-la-planification-local-du-chauffage-et-du-refroidissement\/\" \/>\n<meta property=\"og:site_name\" content=\"Energy Cities\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/energycities.eu\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-17T14:47:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-17T14:49:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/energy-cities.eu\/wp-content\/uploads\/2025\/10\/AdobeStock_467260138-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@b.karas\" \/>\n<meta name=\"twitter:site\" content=\"@energycities\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicolas Raimondi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/#organization\",\"name\":\"Energy Cities\",\"url\":\"https:\/\/energy-cities.eu\/fr\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/energycities.eu\/\",\"https:\/\/www.youtube.com\/channel\/UChIHn2wF76JzuTbAjSMs0hQ\",\"https:\/\/fr.wikipedia.org\/wiki\/Energy_Cities\",\"https:\/\/twitter.com\/energycities\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/energy-cities.eu\/wp-content\/uploads\/2019\/07\/energy-cities-couleur.jpg\",\"contentUrl\":\"https:\/\/energy-cities.eu\/wp-content\/uploads\/2019\/07\/energy-cities-couleur.jpg\",\"width\":3508,\"height\":2587,\"caption\":\"Energy Cities\"},\"image\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/#website\",\"url\":\"https:\/\/energy-cities.eu\/fr\/\",\"name\":\"Energy Cities\",\"description\":\" The European learning community for future-proof cities\",\"publisher\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/energy-cities.eu\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/manque-delan-national-pour-la-planification-local-du-chauffage-et-du-refroidissement\/#primaryimage\",\"url\":\"https:\/\/energy-cities.eu\/wp-content\/uploads\/2025\/10\/AdobeStock_467260138-scaled.jpeg\",\"contentUrl\":\"https:\/\/energy-cities.eu\/wp-content\/uploads\/2025\/10\/AdobeStock_467260138-scaled.jpeg\",\"width\":2560,\"height\":1707,\"caption\":\"Plate with text in a a calendar 3d\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/manque-delan-national-pour-la-planification-local-du-chauffage-et-du-refroidissement\/#webpage\",\"url\":\"https:\/\/energy-cities.eu\/fr\/manque-delan-national-pour-la-planification-local-du-chauffage-et-du-refroidissement\/\",\"name\":\"Manque d'\u00e9lan national pour la planification local du chauffage et du refroidissement - Energy Cities\",\"isPartOf\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/manque-delan-national-pour-la-planification-local-du-chauffage-et-du-refroidissement\/#primaryimage\"},\"datePublished\":\"2025-10-17T14:47:51+00:00\",\"dateModified\":\"2025-10-17T14:49:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/manque-delan-national-pour-la-planification-local-du-chauffage-et-du-refroidissement\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/energy-cities.eu\/fr\/manque-delan-national-pour-la-planification-local-du-chauffage-et-du-refroidissement\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/manque-delan-national-pour-la-planification-local-du-chauffage-et-du-refroidissement\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/energy-cities.eu\/fr\/nous-sommes-un-reseau-europeen-blabla\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Manque d&#8217;\u00e9lan national pour la planification local du chauffage et du refroidissement\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/manque-delan-national-pour-la-planification-local-du-chauffage-et-du-refroidissement\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/manque-delan-national-pour-la-planification-local-du-chauffage-et-du-refroidissement\/#webpage\"},\"author\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/#\/schema\/person\/ab3d69999a4bf4642dc182eb424afc55\"},\"headline\":\"Manque d&rsquo;\u00e9lan national pour la planification local du chauffage et du refroidissement\",\"datePublished\":\"2025-10-17T14:47:51+00:00\",\"dateModified\":\"2025-10-17T14:49:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/manque-delan-national-pour-la-planification-local-du-chauffage-et-du-refroidissement\/#webpage\"},\"wordCount\":1147,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/manque-delan-national-pour-la-planification-local-du-chauffage-et-du-refroidissement\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/energy-cities.eu\/wp-content\/uploads\/2025\/10\/AdobeStock_467260138-scaled.jpeg\",\"articleSection\":[\"Actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/energy-cities.eu\/fr\/manque-delan-national-pour-la-planification-local-du-chauffage-et-du-refroidissement\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/#\/schema\/person\/ab3d69999a4bf4642dc182eb424afc55\",\"name\":\"Nicolas Raimondi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d4f58996f7785ae72b035549936ba9ee?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d4f58996f7785ae72b035549936ba9ee?s=96&d=mm&r=g\",\"caption\":\"Nicolas Raimondi\"},\"sameAs\":[\"https:\/\/twitter.com\/b.karas\"],\"url\":\"https:\/\/energy-cities.eu\/fr\/staff\/n-raimondi\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Manque d'\u00e9lan national pour la planification local du chauffage et du refroidissement - Energy Cities","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/energy-cities.eu\/fr\/manque-delan-national-pour-la-planification-local-du-chauffage-et-du-refroidissement\/","og_locale":"fr_FR","og_type":"article","og_title":"Manque d'\u00e9lan national pour la planification local du chauffage et du refroidissement - Energy Cities","og_description":"En octobre 2023, la nouvelle version de la directive sur l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique (DEE) a \u00e9t\u00e9 publi\u00e9e au Journal officiel de l\u2019Union europ\u00e9enne. Depuis, les \u00c9tats [\u2026]","og_url":"https:\/\/energy-cities.eu\/fr\/manque-delan-national-pour-la-planification-local-du-chauffage-et-du-refroidissement\/","og_site_name":"Energy Cities","article_publisher":"https:\/\/www.facebook.com\/energycities.eu\/","article_published_time":"2025-10-17T14:47:51+00:00","article_modified_time":"2025-10-17T14:49:29+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2025\/10\/AdobeStock_467260138-scaled.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@b.karas","twitter_site":"@energycities","twitter_misc":{"\u00c9crit par":"Nicolas Raimondi","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/energy-cities.eu\/fr\/#organization","name":"Energy Cities","url":"https:\/\/energy-cities.eu\/fr\/","sameAs":["https:\/\/www.facebook.com\/energycities.eu\/","https:\/\/www.youtube.com\/channel\/UChIHn2wF76JzuTbAjSMs0hQ","https:\/\/fr.wikipedia.org\/wiki\/Energy_Cities","https:\/\/twitter.com\/energycities"],"logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/energy-cities.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2019\/07\/energy-cities-couleur.jpg","contentUrl":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2019\/07\/energy-cities-couleur.jpg","width":3508,"height":2587,"caption":"Energy Cities"},"image":{"@id":"https:\/\/energy-cities.eu\/fr\/#\/schema\/logo\/image\/"}},{"@type":"WebSite","@id":"https:\/\/energy-cities.eu\/fr\/#website","url":"https:\/\/energy-cities.eu\/fr\/","name":"Energy Cities","description":" The European learning community for future-proof cities","publisher":{"@id":"https:\/\/energy-cities.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/energy-cities.eu\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/energy-cities.eu\/fr\/manque-delan-national-pour-la-planification-local-du-chauffage-et-du-refroidissement\/#primaryimage","url":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2025\/10\/AdobeStock_467260138-scaled.jpeg","contentUrl":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2025\/10\/AdobeStock_467260138-scaled.jpeg","width":2560,"height":1707,"caption":"Plate with text in a a calendar 3d"},{"@type":"WebPage","@id":"https:\/\/energy-cities.eu\/fr\/manque-delan-national-pour-la-planification-local-du-chauffage-et-du-refroidissement\/#webpage","url":"https:\/\/energy-cities.eu\/fr\/manque-delan-national-pour-la-planification-local-du-chauffage-et-du-refroidissement\/","name":"Manque d'\u00e9lan national pour la planification local du chauffage et du refroidissement - Energy Cities","isPartOf":{"@id":"https:\/\/energy-cities.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/energy-cities.eu\/fr\/manque-delan-national-pour-la-planification-local-du-chauffage-et-du-refroidissement\/#primaryimage"},"datePublished":"2025-10-17T14:47:51+00:00","dateModified":"2025-10-17T14:49:29+00:00","breadcrumb":{"@id":"https:\/\/energy-cities.eu\/fr\/manque-delan-national-pour-la-planification-local-du-chauffage-et-du-refroidissement\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/energy-cities.eu\/fr\/manque-delan-national-pour-la-planification-local-du-chauffage-et-du-refroidissement\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/energy-cities.eu\/fr\/manque-delan-national-pour-la-planification-local-du-chauffage-et-du-refroidissement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/energy-cities.eu\/fr\/nous-sommes-un-reseau-europeen-blabla\/"},{"@type":"ListItem","position":2,"name":"Manque d&#8217;\u00e9lan national pour la planification local du chauffage et du refroidissement"}]},{"@type":"Article","@id":"https:\/\/energy-cities.eu\/fr\/manque-delan-national-pour-la-planification-local-du-chauffage-et-du-refroidissement\/#article","isPartOf":{"@id":"https:\/\/energy-cities.eu\/fr\/manque-delan-national-pour-la-planification-local-du-chauffage-et-du-refroidissement\/#webpage"},"author":{"@id":"https:\/\/energy-cities.eu\/fr\/#\/schema\/person\/ab3d69999a4bf4642dc182eb424afc55"},"headline":"Manque d&rsquo;\u00e9lan national pour la planification local du chauffage et du refroidissement","datePublished":"2025-10-17T14:47:51+00:00","dateModified":"2025-10-17T14:49:29+00:00","mainEntityOfPage":{"@id":"https:\/\/energy-cities.eu\/fr\/manque-delan-national-pour-la-planification-local-du-chauffage-et-du-refroidissement\/#webpage"},"wordCount":1147,"commentCount":0,"publisher":{"@id":"https:\/\/energy-cities.eu\/fr\/#organization"},"image":{"@id":"https:\/\/energy-cities.eu\/fr\/manque-delan-national-pour-la-planification-local-du-chauffage-et-du-refroidissement\/#primaryimage"},"thumbnailUrl":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2025\/10\/AdobeStock_467260138-scaled.jpeg","articleSection":["Actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/energy-cities.eu\/fr\/manque-delan-national-pour-la-planification-local-du-chauffage-et-du-refroidissement\/#respond"]}]},{"@type":"Person","@id":"https:\/\/energy-cities.eu\/fr\/#\/schema\/person\/ab3d69999a4bf4642dc182eb424afc55","name":"Nicolas Raimondi","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/energy-cities.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d4f58996f7785ae72b035549936ba9ee?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d4f58996f7785ae72b035549936ba9ee?s=96&d=mm&r=g","caption":"Nicolas Raimondi"},"sameAs":["https:\/\/twitter.com\/b.karas"],"url":"https:\/\/energy-cities.eu\/fr\/staff\/n-raimondi\/"}]}},"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/energy-cities.eu\/fr\/category\/actualites\/\" class=\"advgb-post-tax-term\">Actualit\u00e9s<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Actualit\u00e9s<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publi\u00e9 11 mois il y a","modified":"Mis \u00e0 jour 11 mois il y a"},"absolute_dates":{"created":"Publi\u00e9 le 17 octobre 2025","modified":"Mise \u00e0 jour le 17 octobre 2025"},"absolute_dates_time":{"created":"Publi\u00e9 le 17 octobre 2025 4:47  ","modified":"Mise \u00e0 jour le 17 octobre 2025 4:49  "},"featured_img_caption":"Plate with text in a a calendar 3d","_links":{"self":[{"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/posts\/91005"}],"collection":[{"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/users\/83"}],"replies":[{"embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/comments?post=91005"}],"version-history":[{"count":8,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/posts\/91005\/revisions"}],"predecessor-version":[{"id":91014,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/posts\/91005\/revisions\/91014"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/media\/90685"}],"wp:attachment":[{"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/media?parent=91005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/categories?post=91005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/tags?post=91005"},{"taxonomy":"hub","embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/hub?post=91005"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/topic?post=91005"},{"taxonomy":"legislative_initiative","embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/legislative_initiative?post=91005"},{"taxonomy":"document_type","embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/document_type?post=91005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}