{"id":9765,"date":"2018-06-29T14:35:10","date_gmt":"2018-06-29T14:35:10","guid":{"rendered":"http:\/\/ec.kuusi.ovh\/?p=9765"},"modified":"2019-01-10T16:06:59","modified_gmt":"2019-01-10T16:06:59","slug":"richesse-des-idees-contre-precarite-energetique","status":"publish","type":"post","link":"https:\/\/energy-cities.eu\/fr\/richesse-des-idees-contre-precarite-energetique\/","title":{"rendered":"RICHESSE DES ID\u00c9ES CONTRE PR\u00c9CARIT\u00c9 \u00c9NERG\u00c9TIQUE"},"content":{"rendered":"\n<p>Au d\u00e9but du mois de juin, la Ville de Cadiz a re\u00e7u le Prix \u00ab&nbsp;<a href=\"https:\/\/www.opendemocracy.net\/tni\/julio-camacho\/tc-cadiz-energy-poverty\">Transformative City<\/a>&nbsp;\u00bb pour son plan d\u2019actions contre la pr\u00e9carit\u00e9 \u00e9nerg\u00e9tique. Ce plan a \u00e9t\u00e9 \u00e9labor\u00e9 par un groupe de ch\u00f4meurs, pr\u00e9alablement form\u00e9s en tant que conseillers \u00e9nergie, et \u00e0 qui la ville a propos\u00e9 un contrat de travail de 8 mois. Avec ce plan, Cadiz fait d\u2019une pierre non pas deux, mais trois coups en s\u2019attaquant au ch\u00f4mage dans la r\u00e9gion, en sensibilisant aux questions \u00e9nerg\u00e9tiques et en aidant les populations dans le besoin.<br><\/p>\n\n\n\n<p>Nous f\u00e9licitons Cadiz pour l\u2019obtention de ce prix et profitons de l\u2019occasion qui nous est donn\u00e9e pour nous int\u00e9resser de plus pr\u00e8s \u00e0 un \u00e9pineux probl\u00e8me. Plus de 50000 foyers en Europe peinent \u00e0 payer leurs factures d\u2019\u00e9nergie et la pr\u00e9carit\u00e9 \u00e9nerg\u00e9tique est depuis longtemps une priorit\u00e9 pour les villes. Derni\u00e8rement, plusieurs bonnes nouvelles en provenance des institutions europ\u00e9ennes ont redonn\u00e9 espoir aux collectivit\u00e9s locales, dont la cr\u00e9ation d\u2019un Observatoire europ\u00e9en de la pr\u00e9carit\u00e9 \u00e9nerg\u00e9tique qui a pour mission d\u2019instaurer un dialogue et de faciliter l\u2019\u00e9change d\u2019informations et de bonnes pratiques sur ce th\u00e8me, et la r\u00e9cente adoption du&nbsp;<a href=\"http:\/\/www.energy-cities.eu\/L-accord-europeen-sur-la-gouvernance-de-l-Union-de-l-energie-ouvre-la-voie-a-la\">r\u00e8glement europ\u00e9en sur la gouvernance de l\u2019Union de l\u2019\u00e9nergie<\/a>, qui impose aux \u00c9tats membres de rendre des comptes dans ce domaine. Cependant, faute de disposer d\u2019une d\u00e9finition juridique qui fasse consensus au sein de l\u2019Union europ\u00e9enne, aucun objectif contraignant ne peut \u00eatre appliqu\u00e9. C\u2019est pourquoi en mai dernier Energy Cities, avec d\u2019autres organismes europ\u00e9ens,a appel\u00e9&nbsp;<a href=\"https:\/\/mailchi.mp\/6ca5b6e4f0e6\/60-organisations-call-on-eu-governments-to-end-energy-poverty\">les gouvernements \u00e0 prendre des mesures dans ce sens.<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img src=\"http:\/\/www.energy-cities.eu\/local\/cache-vignettes\/L350xH110\/logo_mesa_transicion_3_copy-4be85.jpg?1530167462\" alt=\"\"\/><\/figure>\n\n\n\n<p>La plupart des mesures adopt\u00e9es par les gouvernements nationaux portent sur les moyens de limiter le risque pour les personnes en situation de pr\u00e9carit\u00e9 \u00e9nerg\u00e9tique de se voir priv\u00e9es d\u2019\u00e9nergie et sur l\u2019am\u00e9lioration de l\u2019efficacit\u00e9 \u00e9nerg\u00e9tique. Certains vont un peu plus loin et donnent aux m\u00e9nages \u00e0 faibles revenus la possibilit\u00e9 d\u2019acc\u00e9der \u00e0 des tarifs sociaux. En&nbsp;<strong>Flandre&nbsp;<\/strong>(Belgique), par exemple, chaque m\u00e9nage peut b\u00e9n\u00e9ficier d\u2019une r\u00e9duction annuelle sur ses factures, calcul\u00e9e en fonction de la taille du foyer. En&nbsp;<strong>Italie<\/strong>, un plan national mis en place par l\u2019Agence de l\u2019\u00e9nergie avec le soutien des municipalit\u00e9s permet aux m\u00e9nages \u00e0 faibles revenus et aux familles nombreuses de b\u00e9n\u00e9ficier d\u2019une remise sur leurs factures de gaz et d\u2019\u00e9lectricit\u00e9. La France vient de lancer un nouveau syst\u00e8me&nbsp;: au 1er janvier 2018, les tarifs sociaux ont \u00e9t\u00e9 remplac\u00e9s par des \u00ab&nbsp;ch\u00e8ques \u00e9nergie&nbsp;\u00bb que les personnes peuvent utiliser pour payer leurs factures d\u2019\u00e9nergie, mais \u00e9galement pour financer des travaux d\u2019\u00e9conomie d\u2019\u00e9nergie dans leur logement. S\u2019attaquer au probl\u00e8me \u00e0 la source semble en effet \u00eatre le meilleur moyen de le r\u00e9gler.<\/p>\n\n\n\n<p>Avec la vague de remunicipalisation que conna\u00eet l\u2019Europe actuellement, les villes devraient prendre une part de plus en plus active dans la lutte contre la pr\u00e9carit\u00e9 \u00e9nerg\u00e9tique.&nbsp;<strong>Et l\u2019av\u00e8nement d\u2019une gouvernance plus d\u00e9mocratique de l\u2019\u00e9nergie aura des effets positifs, en donnant aux collectivit\u00e9s locales et aux citoyens la possibilit\u00e9 d\u2019apporter leur pierre \u00e0 l\u2019\u00e9difice.<\/strong>&nbsp;Cadiz excelle dans la lutte contre la pr\u00e9carit\u00e9 \u00e9nerg\u00e9tique, mais heureusement elle n\u2019est pas la seule.<\/p>\n\n\n\n<p>A&nbsp;<strong>Berlin<\/strong>, le r\u00e9seau \u00e9lectrique est mis en vente \u00e0 peu pr\u00e8s tous les 15 ans et tout un chacun peut faire une offre d\u2019achat et de gestion du r\u00e9seau. Lors de l\u2019appel d\u2019offres de 2016, les citoyens ont fait pression sur la municipalit\u00e9 pour que la pr\u00e9carit\u00e9 \u00e9nerg\u00e9tique fasse partie des aspects pris en compte.<\/p>\n\n\n\n<p>La Ville de&nbsp;<strong>Plymouth&nbsp;<\/strong>est m\u00eame all\u00e9e plus loin&nbsp;: partant du constat que l\u2019\u00e9nergie citoyenne constituait la meilleure solution pour lutter contre la pr\u00e9carit\u00e9 \u00e9nerg\u00e9tique, la municipalit\u00e9 a jou\u00e9 un r\u00f4le capital dans la cr\u00e9ation de&nbsp;<a href=\"http:\/\/www.plymouthenergycommunity.com\/\">Plymouth Energy Community<\/a>&nbsp;en 2013. Ce collectif rassemble aujourd\u2019hui 1200 individus et organisations qui \u0153uvrent pour une transition vers un syst\u00e8me \u00e9nerg\u00e9tique abordable et \u00e0 faibles \u00e9missions de carbone en permettant aux usagers de b\u00e9n\u00e9ficier de subventions pour effacer leur dette \u00e9nerg\u00e9tique, de conseils pour choisir les meilleurs tarifs et de travaux d\u2019isolation gratuits et subventionn\u00e9s.<\/p>\n\n\n\n<p>Garantir un acc\u00e8s universel \u00e0 l\u2019\u00e9nergie \u00e0 un juste prix est \u00e9galement le leitmotiv de l\u2019entreprise sociale \u00e9cossaise&nbsp;<a href=\"https:\/\/our-power.co.uk\/\">OurPower<\/a>&nbsp;dont les actionnaires sont des bailleurs sociaux, des associations et des collectivit\u00e9s locales. OurPowerest un fournisseur d\u2019\u00e9nergie \u00e0 but non lucratif&nbsp;: l\u2019entreprise produit et vend sa propre \u00e9nergie et tous les b\u00e9n\u00e9fices sont r\u00e9investis au service de ses clients et de la communaut\u00e9. L\u2019approche est similaire \u00e0 celle pr\u00f4n\u00e9e par la&nbsp;<a href=\"https:\/\/www.rescoop.eu\/\">F\u00e9d\u00e9ration europ\u00e9enne des coop\u00e9ratives d\u2019\u00e9nergie renouvelable<\/a>&nbsp;(REScoop)&nbsp;: chaque soci\u00e9taire a acc\u00e8s \u00e0 de l\u2019\u00e9nergie renouvelable produite localement et vendue \u00e0 un prix raisonnable et peut en contr\u00f4ler la fourniture et la distribution.<\/p>\n\n\n\n<p>Il reste encore beaucoup \u00e0 faire pour lutter contre la pr\u00e9carit\u00e9 \u00e9nerg\u00e9tique mais les initiatives qui existent d\u00e9j\u00e0, ainsi que les&nbsp;<a href=\"http:\/\/www.energy-cities.eu\/EU-taking-big-step-forward-toward-energy-democracy\">r\u00e9cents d\u00e9veloppements de la politique \u00e9nerg\u00e9tique europ\u00e9enne<\/a>&nbsp;sont une source d\u2019espoir&nbsp;! Des villes actives et des citoyens engag\u00e9s peuvent faire la diff\u00e9rence et \u00e0 terme, vaincre la pr\u00e9carit\u00e9 \u00e9nerg\u00e9tique gr\u00e2ce \u00e0 la richesse de leurs id\u00e9es&nbsp;!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Au d\u00e9but du mois de juin, la Ville de Cadiz a re\u00e7u le Prix \u00ab&nbsp;Transformative City&nbsp;\u00bb pour son plan d\u2019actions contre la pr\u00e9carit\u00e9 \u00e9nerg\u00e9tique. Ce <a href=\"https:\/\/energy-cities.eu\/fr\/richesse-des-idees-contre-precarite-energetique\/\">[\u2026]<\/a><\/p>\n","protected":false},"author":29,"featured_media":16601,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","ub_ctt_via":""},"categories":[4],"tags":[],"hub":[],"topic":[22],"legislative_initiative":[],"document_type":[],"acf":[],"author_meta":{"display_name":"Sara Giovannini","author_link":"https:\/\/energy-cities.eu\/fr\/staff\/s-giovannini\/"},"featured_img":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2018\/06\/vidar-nordli-mathisen-1369119-unsplash-300x205.jpg","featured_image_src":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2018\/06\/vidar-nordli-mathisen-1369119-unsplash.jpg","author_info":{"display_name":"Sara Giovannini","author_link":"https:\/\/energy-cities.eu\/fr\/staff\/s-giovannini\/"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>RICHESSE DES ID\u00c9ES CONTRE PR\u00c9CARIT\u00c9 \u00c9NERG\u00c9TIQUE - Energy Cities<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/energy-cities.eu\/fr\/richesse-des-idees-contre-precarite-energetique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RICHESSE DES ID\u00c9ES CONTRE PR\u00c9CARIT\u00c9 \u00c9NERG\u00c9TIQUE - Energy Cities\" \/>\n<meta property=\"og:description\" content=\"Au d\u00e9but du mois de juin, la Ville de Cadiz a re\u00e7u le Prix \u00ab&nbsp;Transformative City&nbsp;\u00bb pour son plan d\u2019actions contre la pr\u00e9carit\u00e9 \u00e9nerg\u00e9tique. Ce [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/energy-cities.eu\/fr\/richesse-des-idees-contre-precarite-energetique\/\" \/>\n<meta property=\"og:site_name\" content=\"Energy Cities\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/energycities.eu\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-29T14:35:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-10T16:06:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/energy-cities.eu\/wp-content\/uploads\/2018\/06\/vidar-nordli-mathisen-1369119-unsplash.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"3500\" \/>\n\t<meta property=\"og:image:height\" content=\"2391\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Giovannini_S\" \/>\n<meta name=\"twitter:site\" content=\"@energycities\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sara Giovannini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/#organization\",\"name\":\"Energy Cities\",\"url\":\"https:\/\/energy-cities.eu\/fr\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/energycities.eu\/\",\"https:\/\/www.youtube.com\/channel\/UChIHn2wF76JzuTbAjSMs0hQ\",\"https:\/\/fr.wikipedia.org\/wiki\/Energy_Cities\",\"https:\/\/twitter.com\/energycities\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/energy-cities.eu\/wp-content\/uploads\/2019\/07\/energy-cities-couleur.jpg\",\"contentUrl\":\"https:\/\/energy-cities.eu\/wp-content\/uploads\/2019\/07\/energy-cities-couleur.jpg\",\"width\":3508,\"height\":2587,\"caption\":\"Energy Cities\"},\"image\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/#website\",\"url\":\"https:\/\/energy-cities.eu\/fr\/\",\"name\":\"Energy Cities\",\"description\":\" The European learning community for future-proof cities\",\"publisher\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/energy-cities.eu\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/richesse-des-idees-contre-precarite-energetique\/#primaryimage\",\"url\":\"https:\/\/energy-cities.eu\/wp-content\/uploads\/2018\/06\/vidar-nordli-mathisen-1369119-unsplash.jpg\",\"contentUrl\":\"https:\/\/energy-cities.eu\/wp-content\/uploads\/2018\/06\/vidar-nordli-mathisen-1369119-unsplash.jpg\",\"width\":3500,\"height\":2391},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/richesse-des-idees-contre-precarite-energetique\/#webpage\",\"url\":\"https:\/\/energy-cities.eu\/fr\/richesse-des-idees-contre-precarite-energetique\/\",\"name\":\"RICHESSE DES ID\u00c9ES CONTRE PR\u00c9CARIT\u00c9 \u00c9NERG\u00c9TIQUE - Energy Cities\",\"isPartOf\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/richesse-des-idees-contre-precarite-energetique\/#primaryimage\"},\"datePublished\":\"2018-06-29T14:35:10+00:00\",\"dateModified\":\"2019-01-10T16:06:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/richesse-des-idees-contre-precarite-energetique\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/energy-cities.eu\/fr\/richesse-des-idees-contre-precarite-energetique\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/richesse-des-idees-contre-precarite-energetique\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/energy-cities.eu\/fr\/nous-sommes-un-reseau-europeen-blabla\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RICHESSE DES ID\u00c9ES CONTRE PR\u00c9CARIT\u00c9 \u00c9NERG\u00c9TIQUE\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/richesse-des-idees-contre-precarite-energetique\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/richesse-des-idees-contre-precarite-energetique\/#webpage\"},\"author\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/#\/schema\/person\/73f112310a36882313788a50db45fe68\"},\"headline\":\"RICHESSE DES ID\u00c9ES CONTRE PR\u00c9CARIT\u00c9 \u00c9NERG\u00c9TIQUE\",\"datePublished\":\"2018-06-29T14:35:10+00:00\",\"dateModified\":\"2019-01-10T16:06:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/richesse-des-idees-contre-precarite-energetique\/#webpage\"},\"wordCount\":970,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/richesse-des-idees-contre-precarite-energetique\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/energy-cities.eu\/wp-content\/uploads\/2018\/06\/vidar-nordli-mathisen-1369119-unsplash.jpg\",\"articleSection\":[\"Actualit\u00e9s\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/energy-cities.eu\/fr\/richesse-des-idees-contre-precarite-energetique\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/#\/schema\/person\/73f112310a36882313788a50db45fe68\",\"name\":\"Sara Giovannini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ed06f04ad82b63908c4b0461665a3717?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ed06f04ad82b63908c4b0461665a3717?s=96&d=mm&r=g\",\"caption\":\"Sara Giovannini\"},\"sameAs\":[\"https:\/\/twitter.com\/Giovannini_S\"],\"url\":\"https:\/\/energy-cities.eu\/fr\/staff\/s-giovannini\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RICHESSE DES ID\u00c9ES CONTRE PR\u00c9CARIT\u00c9 \u00c9NERG\u00c9TIQUE - Energy Cities","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/energy-cities.eu\/fr\/richesse-des-idees-contre-precarite-energetique\/","og_locale":"fr_FR","og_type":"article","og_title":"RICHESSE DES ID\u00c9ES CONTRE PR\u00c9CARIT\u00c9 \u00c9NERG\u00c9TIQUE - Energy Cities","og_description":"Au d\u00e9but du mois de juin, la Ville de Cadiz a re\u00e7u le Prix \u00ab&nbsp;Transformative City&nbsp;\u00bb pour son plan d\u2019actions contre la pr\u00e9carit\u00e9 \u00e9nerg\u00e9tique. Ce [\u2026]","og_url":"https:\/\/energy-cities.eu\/fr\/richesse-des-idees-contre-precarite-energetique\/","og_site_name":"Energy Cities","article_publisher":"https:\/\/www.facebook.com\/energycities.eu\/","article_published_time":"2018-06-29T14:35:10+00:00","article_modified_time":"2019-01-10T16:06:59+00:00","og_image":[{"width":3500,"height":2391,"url":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2018\/06\/vidar-nordli-mathisen-1369119-unsplash.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@Giovannini_S","twitter_site":"@energycities","twitter_misc":{"\u00c9crit par":"Sara Giovannini","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/energy-cities.eu\/fr\/#organization","name":"Energy Cities","url":"https:\/\/energy-cities.eu\/fr\/","sameAs":["https:\/\/www.facebook.com\/energycities.eu\/","https:\/\/www.youtube.com\/channel\/UChIHn2wF76JzuTbAjSMs0hQ","https:\/\/fr.wikipedia.org\/wiki\/Energy_Cities","https:\/\/twitter.com\/energycities"],"logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/energy-cities.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2019\/07\/energy-cities-couleur.jpg","contentUrl":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2019\/07\/energy-cities-couleur.jpg","width":3508,"height":2587,"caption":"Energy Cities"},"image":{"@id":"https:\/\/energy-cities.eu\/fr\/#\/schema\/logo\/image\/"}},{"@type":"WebSite","@id":"https:\/\/energy-cities.eu\/fr\/#website","url":"https:\/\/energy-cities.eu\/fr\/","name":"Energy Cities","description":" The European learning community for future-proof cities","publisher":{"@id":"https:\/\/energy-cities.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/energy-cities.eu\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/energy-cities.eu\/fr\/richesse-des-idees-contre-precarite-energetique\/#primaryimage","url":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2018\/06\/vidar-nordli-mathisen-1369119-unsplash.jpg","contentUrl":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2018\/06\/vidar-nordli-mathisen-1369119-unsplash.jpg","width":3500,"height":2391},{"@type":"WebPage","@id":"https:\/\/energy-cities.eu\/fr\/richesse-des-idees-contre-precarite-energetique\/#webpage","url":"https:\/\/energy-cities.eu\/fr\/richesse-des-idees-contre-precarite-energetique\/","name":"RICHESSE DES ID\u00c9ES CONTRE PR\u00c9CARIT\u00c9 \u00c9NERG\u00c9TIQUE - Energy Cities","isPartOf":{"@id":"https:\/\/energy-cities.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/energy-cities.eu\/fr\/richesse-des-idees-contre-precarite-energetique\/#primaryimage"},"datePublished":"2018-06-29T14:35:10+00:00","dateModified":"2019-01-10T16:06:59+00:00","breadcrumb":{"@id":"https:\/\/energy-cities.eu\/fr\/richesse-des-idees-contre-precarite-energetique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/energy-cities.eu\/fr\/richesse-des-idees-contre-precarite-energetique\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/energy-cities.eu\/fr\/richesse-des-idees-contre-precarite-energetique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/energy-cities.eu\/fr\/nous-sommes-un-reseau-europeen-blabla\/"},{"@type":"ListItem","position":2,"name":"RICHESSE DES ID\u00c9ES CONTRE PR\u00c9CARIT\u00c9 \u00c9NERG\u00c9TIQUE"}]},{"@type":"Article","@id":"https:\/\/energy-cities.eu\/fr\/richesse-des-idees-contre-precarite-energetique\/#article","isPartOf":{"@id":"https:\/\/energy-cities.eu\/fr\/richesse-des-idees-contre-precarite-energetique\/#webpage"},"author":{"@id":"https:\/\/energy-cities.eu\/fr\/#\/schema\/person\/73f112310a36882313788a50db45fe68"},"headline":"RICHESSE DES ID\u00c9ES CONTRE PR\u00c9CARIT\u00c9 \u00c9NERG\u00c9TIQUE","datePublished":"2018-06-29T14:35:10+00:00","dateModified":"2019-01-10T16:06:59+00:00","mainEntityOfPage":{"@id":"https:\/\/energy-cities.eu\/fr\/richesse-des-idees-contre-precarite-energetique\/#webpage"},"wordCount":970,"commentCount":0,"publisher":{"@id":"https:\/\/energy-cities.eu\/fr\/#organization"},"image":{"@id":"https:\/\/energy-cities.eu\/fr\/richesse-des-idees-contre-precarite-energetique\/#primaryimage"},"thumbnailUrl":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2018\/06\/vidar-nordli-mathisen-1369119-unsplash.jpg","articleSection":["Actualit\u00e9s"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/energy-cities.eu\/fr\/richesse-des-idees-contre-precarite-energetique\/#respond"]}]},{"@type":"Person","@id":"https:\/\/energy-cities.eu\/fr\/#\/schema\/person\/73f112310a36882313788a50db45fe68","name":"Sara Giovannini","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/energy-cities.eu\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ed06f04ad82b63908c4b0461665a3717?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ed06f04ad82b63908c4b0461665a3717?s=96&d=mm&r=g","caption":"Sara Giovannini"},"sameAs":["https:\/\/twitter.com\/Giovannini_S"],"url":"https:\/\/energy-cities.eu\/fr\/staff\/s-giovannini\/"}]}},"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/energy-cities.eu\/fr\/category\/actualites\/\" class=\"advgb-post-tax-term\">Actualit\u00e9s<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Actualit\u00e9s<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publi\u00e9 8 ans il y a","modified":"Mis \u00e0 jour 8 ans il y a"},"absolute_dates":{"created":"Publi\u00e9 le 29 juin 2018","modified":"Mise \u00e0 jour le 10 janvier 2019"},"absolute_dates_time":{"created":"Publi\u00e9 le 29 juin 2018 2:35  ","modified":"Mise \u00e0 jour le 10 janvier 2019 4:06  "},"featured_img_caption":"","_links":{"self":[{"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/posts\/9765"}],"collection":[{"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/comments?post=9765"}],"version-history":[{"count":3,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/posts\/9765\/revisions"}],"predecessor-version":[{"id":10429,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/posts\/9765\/revisions\/10429"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/media\/16601"}],"wp:attachment":[{"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/media?parent=9765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/categories?post=9765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/tags?post=9765"},{"taxonomy":"hub","embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/hub?post=9765"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/topic?post=9765"},{"taxonomy":"legislative_initiative","embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/legislative_initiative?post=9765"},{"taxonomy":"document_type","embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/document_type?post=9765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}