{"id":10142,"date":"2017-04-09T09:20:39","date_gmt":"2017-04-09T07:20:39","guid":{"rendered":"http:\/\/ec.kuusi.ovh\/?post_type=publications&#038;p=10142"},"modified":"2023-02-21T12:05:20","modified_gmt":"2023-02-21T11:05:20","slug":"la-reappropriation-locale-de-lenergie-en-europe","status":"publish","type":"publications","link":"https:\/\/energy-cities.eu\/fr\/publication\/la-reappropriation-locale-de-lenergie-en-europe\/","title":{"rendered":"La r\u00e9appropriation locale de l&rsquo;\u00e9nergie en Europe"},"content":{"rendered":"\n<p>\u00ab Les villes devraient \u00eatre au centre de la transition \u00e9nerg\u00e9tique \u00bb. Le constat \u00e9manant du dernier rapport de l\u2019Agence Internationale de l\u2019Energie sur les Energy Technology Perspectives est sans appel : avec plus de la moiti\u00e9 de la population et 80 % du PIB mondial, les villes repr\u00e9sentent deux tiers de la demande en \u00e9nergie primaire et 70 % des \u00e9missions de CO2 li\u00e9es \u00e0 l\u2019\u00e9nergie (IEA, 2016). <br> Au-del\u00e0 de leur poids en tant que centres de consommation \u00e9nerg\u00e9tique, les villes sont \u00e9galement un formidable vivier d\u2019initiatives innovantes et ambitieuses en faveur de la transition \u00e9nerg\u00e9tique. <\/p>\n\n\n\n<p>Le facteur politique est certainement le principal argument d\u2019une initiative de r\u00e9appropriation locale et publique de l\u2019\u00e9nergie et ce, quel que soit le pays consid\u00e9r\u00e9. Ainsi, on ne rencontre pas d\u2019exemple, o\u00f9 une initiative de cr\u00e9ation d\u2019une nouvelle entreprise publique locale ou de remunicipalisation de l\u2019\u00e9nergie se ferait dans un seul but \u00e9conomique, d\u00e9pourvue d\u2019une vision politique forte en ce qui concerne la valeur ajout\u00e9e d\u2019un renforcement de la gestion publique de l\u2019\u00e9nergie, g\u00e9n\u00e9ralement associ\u00e9e \u00e0 une strat\u00e9gie ambitieuse en mati\u00e8re de transition \u00e9nerg\u00e9tique locale.<\/p>\n\n\n\n<h3>UN NOUVEAU SOUFFLE \u00c9CONOMIQUE POUR UN TERRITOIRE RURAL FRAN\u00c7AIS : LE MEN\u00c9 <\/h3>\n\n\n\n<p>Avec ses 6500 habitants, la communaut\u00e9 de communes du Men\u00e9 en Bretagne repr\u00e9sente un exemple en mati\u00e8re de transition \u00e9nerg\u00e9tique rurale en France. L\u2019intercommunalit\u00e9 a \u00e9t\u00e9 l\u2019un des pionniers et fondateurs du r\u00e9seau des territoires \u00e0 \u00e9nergie positive (TEPOS). D\u00e8s le d\u00e9but des ann\u00e9es 2000, elle a entrepris une \u00e9tude des gisements d\u2019\u00e9nergies renouvelables (m\u00e9thanisation, \u00e9olien, solaire, bois chaleur, etc.) d\u00e9bouchant en 2005 sur un plan strat\u00e9gique et l\u2019objectif d\u2019atteindre 100 % d\u2019\u00e9nergies renouvelables \u00e0 l\u2019horizon 2025. Sur l\u2019initiative des \u00e9lus, des agriculteurs et des citoyens, le territoire s\u2019est progressivement dot\u00e9 d\u2019une installation de m\u00e9thanisation en cog\u00e9n\u00e9ration, valorisant les lisiers et bio-d\u00e9chets (15 millions d\u2019euros d\u2019investissement), d\u2019une usine d\u2019huiles-carburants (colza), d\u2019un parc \u00e9olien citoyen (8 millions d\u2019euros), de deux r\u00e9seaux de chaleurs, de chaudi\u00e8res-bois, de plusieurs installations solaires et  de   logements sociaux neutres en  \u00e9nergie. Afin de favoriser le d\u00e9veloppement \u00e9conomique local, la collectivit\u00e9 a \u00e9galement cr\u00e9\u00e9 une p\u00e9pini\u00e8re (Menerp\u00f4le) et un parc d\u2019activit\u00e9s sp\u00e9cialis\u00e9 en \u00e9nergies.  <\/p>\n\n\n\n<h3>BRISTOL ENERGY : POUR UNE TRANSITION \u00c9NERG\u00c9TIQUE LOCALE <\/h3>\n\n\n\n<p>La ville de Bristol en Angleterre est connue pour \u00eatre un terreau d\u2019initiatives citoyennes et locales en faveur d\u2019une transition \u00e9cologique, qui lui a valu d\u2019\u00eatre s\u00e9lectionn\u00e9e comme la \u00ab capitale verte \u00bb de l\u2019Europe en 2015. La ville affiche non seulement des objectifs ambitieux en mati\u00e8re de transition \u00e9nerg\u00e9tique &#8211; r\u00e9duire la consommation d\u2019\u00e9nergie de 30 % et les \u00e9missions de CO2 de 40 % entre 2005 et 2020 &#8211; mais \u00e9galement de premiers r\u00e9sultats probants, notamment une baisse de la consommation d\u2019\u00e9nergie de 20 % et des \u00e9missions de CO2 de 18 % jusqu\u2019en 2013 (Bristol, 2015). Inspir\u00e9e par l\u2019exp\u00e9rience des Stadtwerke allemandes et  laur\u00e9ate d\u2019une aide europ\u00e9enne dans le cadre  du programme ELENA, Bristol a con\u00e7u une strat\u00e9gie ambitieuse pour se r\u00e9approprier l\u2019\u00e9nergie \u00e0 l\u2019\u00e9chelle de la ville (Energy Cities, 2015). Celle-ci a d\u00e9bouch\u00e9 en 2016 sur la cr\u00e9ation de sa propre entreprise communale d\u2019\u00e9nergie Bristol Energy.  La priorit\u00e9 de Bristol Energy r\u00e9side dans un premier temps dans la lutte contre la pr\u00e9carit\u00e9 \u00e9nerg\u00e9tique, en proposant des tarifs plus \u00e9quitables aux habitants. A terme, l\u2019entreprise communale doit \u00e9galement s\u2019engager dans le d\u00e9veloppement de la production locale  d\u2019\u00e9nergies renouvelables et dans les services d\u2019efficacit\u00e9 \u00e9nerg\u00e9tique (NEF, 2016). Dans une d\u00e9marche compl\u00e9mentaire, Bristol met \u00e9galement en avant la contribution des projets citoyens d\u2019\u00e9nergie. D\u00e8s 2010, la ville a aid\u00e9 \u00e0 la cr\u00e9ation d\u2019un r\u00e9seau de soutien au d\u00e9veloppement des initiatives citoyennes d\u2019\u00e9nergies renouvelables, Bristol Energy Network, d\u00e9bouchant en 2013 sur l\u2019\u00e9laboration d\u2019une strat\u00e9gie locale de d\u00e9veloppement des projets citoyens (Bristol Energy Network, 2013). La ville a ensuite lanc\u00e9 un fond de soutien d\u00e9di\u00e9 aux projets citoyens d\u2019\u00e9nergies renouvelables, Bristol Community Energy Fund et a \u00e9t\u00e9 partie prenante de la cr\u00e9ation de la coop\u00e9rative citoyenne Bristol Energy Cooperative, qui a d\u00e9j\u00e0 lev\u00e9 plus de 10 millions de livres pour des projets locaux.<\/p>\n\n\n\n<h3>LE FINANCEMENT D\u2019OUTILS INNOVANTS EN FAVEUR DE LA TRANSITION \u00c9NERG\u00c9TIQUE PAR LES STADTWERKE DE HANOVRE, ENERCITY <\/h3>\n\n\n\n<p> Avec un chiffre d\u2019affaires de 2,4 milliards d\u2019euros, l\u2019entreprise communale d\u2019\u00e9nergie de Hanovre, Enercity, est l\u2019un des 10 plus grands fournisseurs publics locaux en Allemagne. Forte de son succ\u00e8s, Enercity a d\u00e9velopp\u00e9 d\u00e8s 1998 un outil de financement innovant au service des actions de baisse des \u00e9missions de gaz \u00e0 effet de serre : le fonds ProKlima. Financ\u00e9 \u00e0 hauteur de 5,5 millions d\u2019euros par an, ce fonds est aliment\u00e9 par une contribution int\u00e9gr\u00e9e au tarif de gaz de la ville (1 million d\u2019euros annuels), un  fl\u00e9chage partiel des profits d\u2019Enercity (3 millions d\u2019euros), ainsi que de contributions d\u2019autres collectivit\u00e9s participantes (Enercity, 2016). L\u2019ensemble des fonds est destin\u00e9 \u00e0 soutenir des actions d\u2019efficacit\u00e9 \u00e9nerg\u00e9tique dans les b\u00e2timents (notamment r\u00e9novations et constructions de maisons passives) et les usages \u00e9lectriques, le d\u00e9veloppement d\u2019\u00e9nergies renouvelables (solaire et chaleur) et le raccordement aux r\u00e9seaux de chaleur et les activit\u00e9s p\u00e9dagogiques li\u00e9es \u00e0 la lutte contre le d\u00e9r\u00e8glement climatique. Depuis sa cr\u00e9ation, le fonds a ainsi permis de verser un total de 60 millions d\u2019euros d\u2019aides jusqu\u2019\u00e0 fin 2015. Au-del\u00e0 de sa transversalit\u00e9 en mati\u00e8re d\u2019actions soutenues et de son mod\u00e8le de financement innovant, le fonds se distingue \u00e9galement par un effet de levier particuli\u00e8rement important entre les fonds publics inject\u00e9s et les investissements  d\u00e9clench\u00e9s : selon une \u00e9tude portant sur l\u2019ann\u00e9e 2010, chaque euro de subvention a permis de d\u00e9clencher 12,7 euros d\u2019investissements en moyenne (G\u00fcnther, 2011). Au total, les 2,6 millions d\u2019euros d\u2019aides vers\u00e9es en 2010 ont ainsi g\u00e9n\u00e9r\u00e9 33 millions d\u2019euros d\u2019investissements pour une cr\u00e9ation de valeur ajout\u00e9e de 47 millions d\u2019euros, dont 42 % directement sur le territoire de Hanovre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le d\u00e9bat sur la gouvernance locale de l\u2019\u00e9nergie est marqu\u00e9 par un foisonnement de concepts dont le contenu exact n\u2019est pas toujours clair. Des notions telles que la \u00ab remunicipalisation \u00bb, la \u00ab d\u00e9centralisation \u00bb, la \u00ab r\u00e9appropriation \u00bb ou encore la \u00ab d\u00e9mocratisation \u00bb de l\u2019\u00e9nergie sont ainsi devenues des symboles forts, \u00e9tendards d\u2019une vision plus politique et territoriale de la transition \u00e9nerg\u00e9tique. <\/p>\n","protected":false},"author":30,"featured_media":19557,"template":"","hub":[310],"topic":[108,109,110],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La r\u00e9appropriation locale de l&#039;\u00e9nergie en Europe - Energy Cities<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/energy-cities.eu\/fr\/publication\/la-reappropriation-locale-de-lenergie-en-europe\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La r\u00e9appropriation locale de l&#039;\u00e9nergie en Europe - Energy Cities\" \/>\n<meta property=\"og:description\" content=\"Le d\u00e9bat sur la gouvernance locale de l\u2019\u00e9nergie est marqu\u00e9 par un foisonnement de concepts dont le contenu exact n\u2019est pas toujours clair. Des notions telles que la \u00ab remunicipalisation \u00bb, la \u00ab d\u00e9centralisation \u00bb, la \u00ab r\u00e9appropriation \u00bb ou encore la \u00ab d\u00e9mocratisation \u00bb de l\u2019\u00e9nergie sont ainsi devenues des symboles forts, \u00e9tendards d\u2019une vision plus politique et territoriale de la transition \u00e9nerg\u00e9tique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/energy-cities.eu\/fr\/publication\/la-reappropriation-locale-de-lenergie-en-europe\/\" \/>\n<meta property=\"og:site_name\" content=\"Energy Cities\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/energycities.eu\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-21T11:05:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/energy-cities.eu\/wp-content\/uploads\/2019\/01\/header_publi_remunicipalisation.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"994\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@energycities\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/#organization\",\"name\":\"Energy Cities\",\"url\":\"https:\/\/energy-cities.eu\/fr\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/energycities.eu\/\",\"https:\/\/www.youtube.com\/channel\/UChIHn2wF76JzuTbAjSMs0hQ\",\"https:\/\/fr.wikipedia.org\/wiki\/Energy_Cities\",\"https:\/\/twitter.com\/energycities\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/energy-cities.eu\/wp-content\/uploads\/2019\/07\/energy-cities-couleur.jpg\",\"contentUrl\":\"https:\/\/energy-cities.eu\/wp-content\/uploads\/2019\/07\/energy-cities-couleur.jpg\",\"width\":3508,\"height\":2587,\"caption\":\"Energy Cities\"},\"image\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/#website\",\"url\":\"https:\/\/energy-cities.eu\/fr\/\",\"name\":\"Energy Cities\",\"description\":\" The European learning community for future-proof cities\",\"publisher\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/energy-cities.eu\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/publication\/la-reappropriation-locale-de-lenergie-en-europe\/#primaryimage\",\"url\":\"https:\/\/energy-cities.eu\/wp-content\/uploads\/2019\/01\/header_publi_remunicipalisation.jpg\",\"contentUrl\":\"https:\/\/energy-cities.eu\/wp-content\/uploads\/2019\/01\/header_publi_remunicipalisation.jpg\",\"width\":2000,\"height\":994},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/publication\/la-reappropriation-locale-de-lenergie-en-europe\/#webpage\",\"url\":\"https:\/\/energy-cities.eu\/fr\/publication\/la-reappropriation-locale-de-lenergie-en-europe\/\",\"name\":\"La r\u00e9appropriation locale de l'\u00e9nergie en Europe - Energy Cities\",\"isPartOf\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/publication\/la-reappropriation-locale-de-lenergie-en-europe\/#primaryimage\"},\"datePublished\":\"2017-04-09T07:20:39+00:00\",\"dateModified\":\"2023-02-21T11:05:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/energy-cities.eu\/fr\/publication\/la-reappropriation-locale-de-lenergie-en-europe\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/energy-cities.eu\/fr\/publication\/la-reappropriation-locale-de-lenergie-en-europe\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/energy-cities.eu\/fr\/publication\/la-reappropriation-locale-de-lenergie-en-europe\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/energy-cities.eu\/fr\/nous-sommes-un-reseau-europeen-blabla\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La r\u00e9appropriation locale de l'\u00e9nergie en Europe\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La r\u00e9appropriation locale de l'\u00e9nergie en Europe - Energy Cities","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/energy-cities.eu\/fr\/publication\/la-reappropriation-locale-de-lenergie-en-europe\/","og_locale":"fr_FR","og_type":"article","og_title":"La r\u00e9appropriation locale de l'\u00e9nergie en Europe - Energy Cities","og_description":"Le d\u00e9bat sur la gouvernance locale de l\u2019\u00e9nergie est marqu\u00e9 par un foisonnement de concepts dont le contenu exact n\u2019est pas toujours clair. Des notions telles que la \u00ab remunicipalisation \u00bb, la \u00ab d\u00e9centralisation \u00bb, la \u00ab r\u00e9appropriation \u00bb ou encore la \u00ab d\u00e9mocratisation \u00bb de l\u2019\u00e9nergie sont ainsi devenues des symboles forts, \u00e9tendards d\u2019une vision plus politique et territoriale de la transition \u00e9nerg\u00e9tique.","og_url":"https:\/\/energy-cities.eu\/fr\/publication\/la-reappropriation-locale-de-lenergie-en-europe\/","og_site_name":"Energy Cities","article_publisher":"https:\/\/www.facebook.com\/energycities.eu\/","article_modified_time":"2023-02-21T11:05:20+00:00","og_image":[{"width":2000,"height":994,"url":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2019\/01\/header_publi_remunicipalisation.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@energycities","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/energy-cities.eu\/fr\/#organization","name":"Energy Cities","url":"https:\/\/energy-cities.eu\/fr\/","sameAs":["https:\/\/www.facebook.com\/energycities.eu\/","https:\/\/www.youtube.com\/channel\/UChIHn2wF76JzuTbAjSMs0hQ","https:\/\/fr.wikipedia.org\/wiki\/Energy_Cities","https:\/\/twitter.com\/energycities"],"logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/energy-cities.eu\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2019\/07\/energy-cities-couleur.jpg","contentUrl":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2019\/07\/energy-cities-couleur.jpg","width":3508,"height":2587,"caption":"Energy Cities"},"image":{"@id":"https:\/\/energy-cities.eu\/fr\/#\/schema\/logo\/image\/"}},{"@type":"WebSite","@id":"https:\/\/energy-cities.eu\/fr\/#website","url":"https:\/\/energy-cities.eu\/fr\/","name":"Energy Cities","description":" The European learning community for future-proof cities","publisher":{"@id":"https:\/\/energy-cities.eu\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/energy-cities.eu\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/energy-cities.eu\/fr\/publication\/la-reappropriation-locale-de-lenergie-en-europe\/#primaryimage","url":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2019\/01\/header_publi_remunicipalisation.jpg","contentUrl":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2019\/01\/header_publi_remunicipalisation.jpg","width":2000,"height":994},{"@type":"WebPage","@id":"https:\/\/energy-cities.eu\/fr\/publication\/la-reappropriation-locale-de-lenergie-en-europe\/#webpage","url":"https:\/\/energy-cities.eu\/fr\/publication\/la-reappropriation-locale-de-lenergie-en-europe\/","name":"La r\u00e9appropriation locale de l'\u00e9nergie en Europe - Energy Cities","isPartOf":{"@id":"https:\/\/energy-cities.eu\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/energy-cities.eu\/fr\/publication\/la-reappropriation-locale-de-lenergie-en-europe\/#primaryimage"},"datePublished":"2017-04-09T07:20:39+00:00","dateModified":"2023-02-21T11:05:20+00:00","breadcrumb":{"@id":"https:\/\/energy-cities.eu\/fr\/publication\/la-reappropriation-locale-de-lenergie-en-europe\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/energy-cities.eu\/fr\/publication\/la-reappropriation-locale-de-lenergie-en-europe\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/energy-cities.eu\/fr\/publication\/la-reappropriation-locale-de-lenergie-en-europe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/energy-cities.eu\/fr\/nous-sommes-un-reseau-europeen-blabla\/"},{"@type":"ListItem","position":2,"name":"La r\u00e9appropriation locale de l'\u00e9nergie en Europe"}]}]}},"featured_img":"https:\/\/energy-cities.eu\/wp-content\/uploads\/2019\/01\/header_publi_remunicipalisation.jpg","coauthors":[],"author_meta":{"author_link":"https:\/\/energy-cities.eu\/fr\/staff\/b-karas\/","display_name":"Beatrice Karas"},"relative_dates":{"created":"Publi\u00e9 9 ans il y a","modified":"Mis \u00e0 jour 3 ans il y a"},"absolute_dates":{"created":"Publi\u00e9 le 09 avril 2017","modified":"Mise \u00e0 jour le 21 f\u00e9vrier 2023"},"absolute_dates_time":{"created":"Publi\u00e9 le 09 avril 2017 9:20  ","modified":"Mise \u00e0 jour le 21 f\u00e9vrier 2023 12:05  "},"featured_img_caption":"","tax_additional":{"hub":{"linked":["<a href=\"https:\/\/energy-cities.eu\/fr\/hub\/gouvernance-locale\/\" class=\"advgb-post-tax-term\">Gouvernance locale<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Gouvernance locale<\/span>"],"slug":"hub","name":"Hubs"},"topic":{"linked":["<a href=\"https:\/\/energy-cities.eu\/fr\/th\u00e9matique\/democratie-energetique\/\" class=\"advgb-post-tax-term\">D\u00e9mocratie \u00e9nerg\u00e9tique<\/a>","<a href=\"https:\/\/energy-cities.eu\/fr\/th\u00e9matique\/cooperation-fr\/\" class=\"advgb-post-tax-term\">Coop\u00e9ration<\/a>","<a href=\"https:\/\/energy-cities.eu\/fr\/th\u00e9matique\/planification-vision\/\" class=\"advgb-post-tax-term\">Vision &amp; Planification urbaine<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">D\u00e9mocratie \u00e9nerg\u00e9tique<\/span>","<span class=\"advgb-post-tax-term\">Coop\u00e9ration<\/span>","<span class=\"advgb-post-tax-term\">Vision &amp; Planification urbaine<\/span>"],"slug":"topic","name":"Topics"}},"_links":{"self":[{"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/publications\/10142"}],"collection":[{"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/publications"}],"about":[{"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/types\/publications"}],"author":[{"embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/users\/30"}],"version-history":[{"count":5,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/publications\/10142\/revisions"}],"predecessor-version":[{"id":60983,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/publications\/10142\/revisions\/60983"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/media\/19557"}],"wp:attachment":[{"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/media?parent=10142"}],"wp:term":[{"taxonomy":"hub","embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/hub?post=10142"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/energy-cities.eu\/fr\/wp-json\/wp\/v2\/topic?post=10142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}